{"id":56,"count":1,"description":"","link":"https:\/\/mca-concept.com\/de\/kategorie\/meister\/","name":"Meister","slug":"meister","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Archives des Meister | MCA Concept<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mca-concept.com\/de\/kategorie\/meister\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Meister\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mca-concept.com\/de\/kategorie\/meister\/\" \/>\n<meta property=\"og:site_name\" content=\"MCA Concept\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@McaConcept\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/kategorie\\\/meister\\\/\",\"url\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/kategorie\\\/meister\\\/\",\"name\":\"Archives des Meister | MCA Concept\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/kategorie\\\/meister\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/kategorie\\\/meister\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meister\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/\",\"name\":\"MCA Concept\",\"description\":\"Solutions de gestion d&#039;entreprise ERP-CRM-CMS\",\"publisher\":{\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/#organization\",\"name\":\"MCA Concept\",\"url\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mca-concept.com\\\/wordpress3\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/mca-logo300px.png\",\"contentUrl\":\"https:\\\/\\\/mca-concept.com\\\/wordpress3\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/mca-logo300px.png\",\"width\":300,\"height\":156,\"caption\":\"MCA Concept\"},\"image\":{\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mcaconcept\\\/\",\"https:\\\/\\\/x.com\\\/McaConcept\",\"https:\\\/\\\/www.instagram.com\\\/mcaconcept\\\/\",\"https:\\\/\\\/ch.linkedin.com\\\/company\\\/mca-concept\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC1WT0RmNiTycrnzr6FqDuPg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Archives des Meister | MCA Concept","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mca-concept.com\/de\/kategorie\/meister\/","og_locale":"de_DE","og_type":"article","og_title":"Archives des Meister","og_url":"https:\/\/mca-concept.com\/de\/kategorie\/meister\/","og_site_name":"MCA Concept","twitter_card":"summary_large_image","twitter_site":"@McaConcept","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mca-concept.com\/de\/kategorie\/meister\/","url":"https:\/\/mca-concept.com\/de\/kategorie\/meister\/","name":"Archives des Meister | MCA Concept","isPartOf":{"@id":"https:\/\/mca-concept.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/mca-concept.com\/de\/kategorie\/meister\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/mca-concept.com\/de\/kategorie\/meister\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mca-concept.com\/de\/"},{"@type":"ListItem","position":2,"name":"Meister"}]},{"@type":"WebSite","@id":"https:\/\/mca-concept.com\/de\/#website","url":"https:\/\/mca-concept.com\/de\/","name":"MCA Concept","description":"Solutions de gestion d&#039;entreprise ERP-CRM-CMS","publisher":{"@id":"https:\/\/mca-concept.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mca-concept.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mca-concept.com\/de\/#organization","name":"MCA Concept","url":"https:\/\/mca-concept.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mca-concept.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2019\/09\/mca-logo300px.png","contentUrl":"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2019\/09\/mca-logo300px.png","width":300,"height":156,"caption":"MCA Concept"},"image":{"@id":"https:\/\/mca-concept.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mcaconcept\/","https:\/\/x.com\/McaConcept","https:\/\/www.instagram.com\/mcaconcept\/","https:\/\/ch.linkedin.com\/company\/mca-concept","https:\/\/www.youtube.com\/channel\/UC1WT0RmNiTycrnzr6FqDuPg"]}]}},"_links":{"self":[{"href":"https:\/\/mca-concept.com\/de\/wp-json\/wp\/v2\/categories\/56","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mca-concept.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mca-concept.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/mca-concept.com\/de\/wp-json\/wp\/v2\/posts?categories=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}