{"id":34336,"date":"2022-03-10T14:08:46","date_gmt":"2022-03-10T13:08:46","guid":{"rendered":"https:\/\/mca-concept.com\/ihre-loesungen\/mca-store\/"},"modified":"2025-02-06T14:08:43","modified_gmt":"2025-02-06T13:08:43","slug":"mca-store","status":"publish","type":"page","link":"https:\/\/mca-concept.com\/de\/berufssoftware\/mca-store\/","title":{"rendered":"L\u00f6sung MCA Store"},"content":{"rendered":"<p><div class=\"et_d4_element et_pb_section et_pb_section_0 et_animated  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_0  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_0  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_cta_0 et_pb_promo  et_pb_text_align_center et_pb_bg_layout_dark\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_promo_description\"><h1 class=\"et_pb_module_header\">Software f\u00fcr die Verwaltung von Gesch\u00e4ften<\/h1><div data-et-multi-view=\"{&quot;schema&quot;:{&quot;content&quot;:{&quot;desktop&quot;:&quot;&lt;p&gt;Halten Sie Ihre Warenbest\\u00e4nde im Gleichgewicht, kassieren Sie und erstellen Sie Rechnungen und Bestellscheine ganz einfach mit einer integrierten Kassensoftware f\\u00fcr Gesch\\u00e4fte.&lt;\\\/p&gt;&quot;,&quot;tablet&quot;:&quot;&lt;p&gt;Halten Sie Ihre Warenbest\\u00e4nde im Gleichgewicht, kassieren Sie und erstellen Sie Rechnungen und Bestellscheine ganz einfach mit einer Kassensoftware f\\u00fcr Gesch\\u00e4fte.&lt;\\\/p&gt;&quot;},&quot;target&quot;:&quot;&quot;,&quot;hover_selector&quot;:&quot;&quot;},&quot;slug&quot;:&quot;et_pb_cta&quot;}\" data-et-multi-view-load-tablet-hidden=\"true\"><p>Halten Sie Ihre Warenbest\u00e4nde im Gleichgewicht, kassieren Sie und erstellen Sie Rechnungen und Bestellscheine ganz einfach mit einer integrierten Kassensoftware f\u00fcr Gesch\u00e4fte.<\/p><\/div><\/div>\n\t\t\t\t<div class=\"et_pb_button_wrapper\"><a class=\"et_pb_button et_pb_promo_button\" href=\"#offre\" data-icon=\"5\">Ein Angebot anfordern<\/a><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_1  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_0 et_animated et-waypoint\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"640\" height=\"487\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2023\/01\/logiciel-gestion-magasin-4.png\" alt=\"Violettes Logo, das eine Ladenfront eines Einzelhandelsgesch\u00e4fts darstelltde d\u00e9tail\" title=\"\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2023\/01\/logiciel-gestion-magasin-4.png 640w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2023\/01\/logiciel-gestion-magasin-4-480x365.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 640px, 100vw\" class=\"wp-image-60765\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_1  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_1  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_2  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Flexible Shopsoftware<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_1  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>MCA Store wird in drei Grundversionen mit einem mehr oder weniger umfangreichen Funktionsspektrum angeboten.<\/p>\n<p>Es ist m\u00f6glich, diese Pakete mit weiteren Funktionen anzupassen, so dass Sie eine L\u00f6sung erhalten, die den Bed\u00fcrfnissen Ihres Unternehmens voll entspricht.<\/p>\n<p>Ist Ihr Gesch\u00e4ft mit einer Fertigungs- oder Reparaturwerkstatt verbunden ? F\u00fcgen Sie die Verwaltung von Terminpl\u00e4nen f\u00fcr Ihre Hersteller oder Techniker hinzu. Sie m\u00fcssen derzeit keine Mitarbeiter verwalten, planen aber, in einigen Monaten zus\u00e4tzliches Personal einzustellen ? Lassen Sie die HR-Funktionen in Ihrem Abonnement zum richtigen Zeitpunkt aktivieren.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"packs\" class=\"et_d4_element et_pb_section et_pb_section_2 et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_2  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_3  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_2  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Packs MCA Store SO-1200 bis SO-1600<\/h2><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_3 et_pb_equal_columns et_pb_gutters2  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_4  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_1\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"356\" height=\"141\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store.png\" alt=\"Logo, das einen Parkplatz f\u00fcr die Parkraumbewirtschaftung darstellt\" title=\"logo-logo-software-store\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store.png 356w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store-300x119.png 300w\" sizes=\"(max-width: 356px) 100vw, 356px\" class=\"wp-image-80639\" \/><\/span>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_3  et_pb_text_align_center et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>SO-1200<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_0_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_0 et_pb_bg_layout_light et_block_module\" href=\"#offre\" data-icon=\"5\">Ein Angebot anfordern<\/a>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_divider et_pb_divider_0 et_pb_divider_position_center et_pb_space\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_0 books-bullet-5  et_pb_text_align_left  et_pb_blurb_position_top et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><ul>\n<li style=\"text-align: left;\">Verwaltung<\/li>\n<li style=\"text-align: left;\">Registrierkasse \"Software\"<\/li>\n<li style=\"text-align: left;\">Logistik<\/li>\n<li style=\"text-align: left;\">Kauf, mehrere W\u00e4hrungen<\/li>\n<li style=\"text-align: left;\">Verkauf Kundenmanagement, mehrere W\u00e4hrungen<\/li>\n<li style=\"text-align: left;\">Finanzen<\/li>\n<li style=\"text-align: left;\">Allgemeine Buchhaltung, mehrere W\u00e4hrungen<\/li>\n<li style=\"text-align: left;\">Rechnungszahlung (Lieferanten)<\/li>\n<\/ul><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_1_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_1 et_pb_bg_layout_light et_block_module\" href=\"#Pack_1\" data-icon=\"5\">Details des Pakets<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_5  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_2\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"356\" height=\"141\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store.png\" alt=\"Logo, das einen Parkplatz f\u00fcr die Parkraumbewirtschaftung darstellt\" title=\"logo-logo-software-store\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store.png 356w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store-300x119.png 300w\" sizes=\"(max-width: 356px) 100vw, 356px\" class=\"wp-image-80639\" \/><\/span>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_4  et_pb_text_align_center et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>SO-1400<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_2_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_2 et_pb_bg_layout_light et_block_module\" href=\"#offre\" data-icon=\"5\">Ein Angebot anfordern<\/a>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_divider et_pb_divider_1 et_pb_divider_position_center et_pb_space\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_1 books-bullet-5  et_pb_text_align_left  et_pb_blurb_position_top et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><ul>\n<li style=\"text-align: left;\">Verwaltung<\/li>\n<li style=\"text-align: left;\">Registrierkasse \"Software\"<\/li>\n<li style=\"text-align: left;\">Logistik<\/li>\n<li style=\"text-align: left;\">Kauf, mehrere W\u00e4hrungen<\/li>\n<li style=\"text-align: left;\"><strong>Kredit kaufen<\/strong><\/li>\n<li style=\"text-align: left;\">Verkauf Kundenmanagement, mehrere W\u00e4hrungen<\/li>\n<li style=\"text-align: left;\"><strong>Verkauf von Krediten<\/strong><\/li>\n<li style=\"text-align: left;\">Finanzen<\/li>\n<li style=\"text-align: left;\">Allgemeine Buchhaltung, mehrere W\u00e4hrungen<\/li>\n<li style=\"text-align: left;\">Rechnungszahlung (Lieferanten)<\/li>\n<li style=\"text-align: left;\"><strong>Humanressourcen<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>HR-Mitarbeiter (Geh\u00e4lter)<\/strong><\/li>\n<\/ul><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_3_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_3 et_pb_bg_layout_light et_block_module\" href=\"#Pack_2\" data-icon=\"5\">Details des Pakets<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_6  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_3\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"356\" height=\"141\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store.png\" alt=\"Logo, das einen Parkplatz f\u00fcr die Parkraumbewirtschaftung darstellt\" title=\"logo-logo-software-store\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store.png 356w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store-300x119.png 300w\" sizes=\"(max-width: 356px) 100vw, 356px\" class=\"wp-image-80639\" \/><\/span>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_5  et_pb_text_align_center et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>SO-1600<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_4_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_4 et_pb_bg_layout_light et_block_module\" href=\"#offre\" data-icon=\"5\">Ein Angebot anfordern<\/a>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_divider et_pb_divider_2 et_pb_divider_position_center et_pb_space\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_2 books-bullet-5  et_pb_text_align_left  et_pb_blurb_position_top et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><ul>\n<li style=\"text-align: left;\">Verwaltung<\/li>\n<li style=\"text-align: left;\">Registrierkasse \"Software\"<\/li>\n<li style=\"text-align: left;\">Logistik<\/li>\n<li style=\"text-align: left;\">Kauf, mehrere W\u00e4hrungen<\/li>\n<li style=\"text-align: left;\">Kredit kaufen<\/li>\n<li style=\"text-align: left;\">Verkauf Kundenmanagement, mehrere W\u00e4hrungen<\/li>\n<li style=\"text-align: left;\">Verkauf von Krediten<\/li>\n<li style=\"text-align: left;\">Finanzen<\/li>\n<li style=\"text-align: left;\">Allgemeine Buchhaltung, mehrere W\u00e4hrungen<\/li>\n<li style=\"text-align: left;\">Rechnungszahlung (Lieferanten)<\/li>\n<li style=\"text-align: left;\">Humanressourcen<\/li>\n<li style=\"text-align: left;\">HR-Mitarbeiter (Geh\u00e4lter)<\/li>\n<li style=\"text-align: left;\"><strong>HR-Zeitverwaltung<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>HR-Planung und Urlaubssaldo<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>Projektmanagement<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>Kundendossier<\/strong><\/li>\n<li style=\"text-align: left;\"><strong>Projektmanagement, Kunden<\/strong><\/li>\n<\/ul><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_5_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_5 et_pb_bg_layout_light et_block_module\" href=\"#Pack_3\" data-icon=\"5\">Details des Pakets<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_3  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div id=\"Details\" class=\"et_d4_element et_pb_row et_pb_row_4  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_7  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_6  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2 style=\"text-align: center;\">Details der Funktionen<\/h2>\n<p style=\"text-align: center;\">Hier finden Sie eine vollst\u00e4ndige Liste der Funktionen der Software, je nachdem, welches Paket Sie ben\u00f6tigen.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_5 et_pb_gutters2  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_8  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_7  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2><strong>Verwaltung<\/strong><\/h2>\n<p>- Benutzerverwaltung, Passwort<br \/>- Verwaltung der Zugriffsrechte der Benutzer<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_8  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2><strong>Registrierkasse \"Software\"<br \/><\/strong><\/h2>\n<p>\u2022 Touch-Kasse, MAC, PC, Android<br \/>\u2022 T\u00e4gliche Aufschl\u00fcsselung der Buchhaltung<br \/>\u2022 Bestandsverwaltung<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_9  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Logistik<\/h2>\n<p><strong>Einkauf, mehrere W\u00e4hrungen<\/strong><br \/>- Verwaltung der erbrachten Leistungen<br \/>- Verwaltung der Produkte<br \/>- Verwaltung der Barcodes<br \/>- Verwaltung der Konten ' Aufwand, Umsatz'<br \/>- MwSt. pro Produkt<br \/>- Verwaltung der Lieferanten<br \/>- Nebenbuchhaltung der Lieferanten  <\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_10  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p><strong>Einkauf Kredit<br \/><\/strong>- Verwaltung von Warenr\u00fccksendungen (Lieferanten)<br \/>- Verwaltung von Gutschriften (Lieferanten)<br \/>- Verwaltung von offenen Anzahlungen (Lieferanten)<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_11  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p><strong>Verkauf Kundenverwaltung, mehrere W\u00e4hrungen<br \/><\/strong>- Kundenverwaltung mit Berichten<br \/>- Nebenbuchhaltung der Kunden<br \/>- Angebote, Auftragsscheine, Arbeitsbl\u00e4tter<br \/>- Rechnungen, QR-Code - IBAN pdf<br \/>- Verwaltung mehrerer Korrespondenten pro Rechnung<br \/>- Versand von Angeboten und Rechnungen im pdf-Format per E-Mail<br \/>- Inkasso - camt054 - iso: 20022<br \/>- Tabelle der offenen Rechnungen mit Mahnungen<br \/>- Diagramm<br \/>- Versand von Dokumenten per Mail<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_9  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_12  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p><strong>Kreditverkauf<br \/><\/strong>- Verwaltung von Warenr\u00fccksendungen (Kunden)<br \/>- Verwaltung von Gutschriften (Kunden)<br \/>- Verwaltung von offenen Anzahlungen (Kunden)<br \/>- Verwaltung von Geschenkgutscheinen (Kunden)<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_13  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Finanzen<\/h2>\n<p><strong>Allgemeine Buchhaltung, mehrere W\u00e4hrungen<\/strong><br \/>- Buchungsjournal<br \/>- Konten\u00fcbersicht<br \/>- Benutzerdefinierte Konten (analytische Buchhaltung)<br \/>- Debitoren- und Kreditorenkontenverwaltung<br \/>- MwSt.-Inkrementierung und Abrechnungen<br \/>- PDF-Enddruck<br \/>- Analyse nach Konto<br \/>- MwSt.-Abrechnungen<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_14  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p><strong>Zahlungen von Rechnungen (Lieferanten)<br \/><\/strong>- Zahlungsplan<br \/>- Kreditoren-Nebenbuchhaltung<br \/>- Analyse der Zahlungen nach Periode<br \/>- Verwaltung der Abschreibungen<\/p>\n<p><strong>Zusammenf\u00fchrung von Zahlungen<\/strong><br \/>- Postfinance OPAE-FDS - iso :20022<br \/>- Banken DTA (pain001) - EBICS - iso : 20022<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_10  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_15  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Humanressourcen<\/h2>\n<p><strong>HR-Angestellte (L\u00f6hne und Geh\u00e4lter)<\/strong><br \/>- Lohnauswahl nach Berufsgruppe<br \/>- Verwaltung der Sozialversicherungsabrechnungen<br \/>- Verwaltung der Arbeitgeberkosten<br \/>- Versicherungsdokumente<br \/>- Nebenbuchhaltung<br \/>- Verbunden mit Hauptbuchhaltung <\/p>\n<p><strong>HR-Zeitwirtschaft<br \/><\/strong>\u2022 Zeitmanagement in der Produktion<br \/>\u2022 Zeitmanagement der Mitarbeiter<br \/>\u2022 Verwaltung von Arbeitsbl\u00e4ttern<\/p>\n<p><strong>Personalplanung und Urlaubssaldo<br \/><\/strong>\u2022 Zeitplan, Woche, Monat, Jahr, Stundenzahl  <\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_16  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Projektmanagement<\/h2>\n<p><strong>Kundenakten<\/strong><br \/>- Zentrale Verwaltung von Kunden\/Lieferanten<br \/>- Zentrale Verwaltung von Debitorenrechnungen\/Produkten nach Lieferanten<br \/>- Speicherung von Dokumenten, die sich auf die Akte beziehen<br \/>- Verwaltung der den Zeitpl\u00e4nen zugewiesenen Daten<br \/>- Zentrale Verwaltung von CRM-Datenbl\u00e4ttern<br \/>- Zentrale Verwaltung von durch CMS erstellten Vertr\u00e4gen<br \/>- Dieses Modul, das mit dem Projektmanagement verbunden ist, bietet eine monet\u00e4re Sichtbarkeit.<\/p>\n<p><strong>Projektmanagement, Kunden<br \/><\/strong>- Projektmanagement \/ Mandate \/ W\u00e4hrungsvision<br \/>- Verfolgung von Angeboten, Rechnungen, Zahlungseing\u00e4ngen, Kunden<br \/>- Verfolgung von Angeboten, Rechnungen, Zahlungseing\u00e4ngen, Lieferanten<br \/>- Dieses Modul kann mit dem Modul Akten verkn\u00fcpft werden.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_6  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_11  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_divider et_pb_divider_3 et_pb_space\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"Pack_1\" class=\"et_d4_element et_pb_row et_pb_row_7  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_12  et_pb_css_mix_blend_mode et_block_column et_pb_column_empty\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_13  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_4\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"356\" height=\"141\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store.png\" alt=\"Logo, das einen Parkplatz f\u00fcr die Parkraumbewirtschaftung darstellt\" title=\"logo-logo-software-store\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store.png 356w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store-300x119.png 300w\" sizes=\"(max-width: 356px) 100vw, 356px\" class=\"wp-image-80639\" \/><\/span>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_17  et_pb_text_align_center et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>SO-1200<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_14  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_button_module_wrapper et_pb_button_6_wrapper et_pb_button_alignment_right et_pb_button_alignment_tablet_center et_pb_button_alignment_phone_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_6 et_pb_bg_layout_light et_block_module\" href=\"#offre\" data-icon=\"5\">Ein Angebot anfordern<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_8 et_pb_gutters2  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_15  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_18  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2><strong>Verwaltung<\/strong><\/h2>\n<p>- Benutzerverwaltung, Passwort<br \/>- Verwaltung der Zugriffsrechte der Benutzer<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_19  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2><strong>Registrierkasse \"Software\"<br \/><\/strong><\/h2>\n<p>\u2022 Touch-Kasse, MAC, PC, Android<br \/>\u2022 T\u00e4gliche Aufschl\u00fcsselung der Buchhaltung<br \/>\u2022 Bestandsverwaltung<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_16  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_20  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Logistik<\/h2>\n<p><strong>Einkauf, mehrere W\u00e4hrungen<\/strong><br \/>- Verwaltung der erbrachten Leistungen<br \/>- Verwaltung der Produkte<br \/>- Verwaltung der Barcodes<br \/>- Verwaltung der Konten ' Aufwand, Umsatz'<br \/>- MwSt. pro Produkt<br \/>- Verwaltung der Lieferanten<br \/>- Nebenbuchhaltung der Lieferanten  <\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_21  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p><strong>Verkauf Kundenverwaltung, mehrere W\u00e4hrungen<br \/><\/strong>- Kundenverwaltung mit Berichten<br \/>- Nebenbuchhaltung der Kunden<br \/>- Angebote, Auftragsscheine, Arbeitsbl\u00e4tter<br \/>- Rechnungen, QR-Code - IBAN pdf<br \/>- Verwaltung mehrerer Korrespondenten pro Rechnung<br \/>- Versand von Angeboten und Rechnungen im pdf-Format per E-Mail<br \/>- Inkasso - camt054 - iso: 20022<br \/>- Tabelle der offenen Rechnungen mit Mahnungen<br \/>- Diagramm<br \/>- Versand von Dokumenten per Mail<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_17  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_22  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Finanzen<\/h2>\n<p><strong>Allgemeine Buchhaltung, mehrere W\u00e4hrungen<\/strong><br \/>- Buchungsjournal<br \/>- Konten\u00fcbersicht<br \/>- Benutzerdefinierte Konten (analytische Buchhaltung)<br \/>- Debitoren- und Kreditorenkontenverwaltung<br \/>- MwSt.-Inkrementierung und Abrechnungen<br \/>- PDF-Enddruck<br \/>- Analyse nach Konto<br \/>- MwSt.-Abrechnungen<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_23  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p><strong>Zahlungen von Rechnungen (Lieferanten)<br \/><\/strong>- Zahlungsplan<br \/>- Kreditoren-Nebenbuchhaltung<br \/>- Analyse der Zahlungen nach Periode<br \/>- Verwaltung der Abschreibungen<\/p>\n<p><strong>Zusammenf\u00fchrung von Zahlungen<\/strong><br \/>- Postfinance OPAE-FDS - iso :20022<br \/>- Banken DTA (pain001) - EBICS - iso : 20022<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_9  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_18  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_divider et_pb_divider_4 et_pb_space\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"Pack_2\" class=\"et_d4_element et_pb_row et_pb_row_10  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_19  et_pb_css_mix_blend_mode et_block_column et_pb_column_empty\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_20  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_5\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"356\" height=\"141\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store.png\" alt=\"Logo, das einen Parkplatz f\u00fcr die Parkraumbewirtschaftung darstellt\" title=\"logo-logo-software-store\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store.png 356w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store-300x119.png 300w\" sizes=\"(max-width: 356px) 100vw, 356px\" class=\"wp-image-80639\" \/><\/span>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_24  et_pb_text_align_center et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>SO-1400<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_21  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_button_module_wrapper et_pb_button_7_wrapper et_pb_button_alignment_right et_pb_button_alignment_tablet_center et_pb_button_alignment_phone_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_7 et_pb_bg_layout_light et_block_module\" href=\"#offre\" data-icon=\"5\">Ein Angebot anfordern<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_11 et_pb_gutters2  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_22  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_25  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2><strong>Verwaltung<\/strong><\/h2>\n<p>- Benutzerverwaltung, Passwort<br \/>- Verwaltung der Zugriffsrechte der Benutzer<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_26  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2><strong>Registrierkasse \"Software\"<br \/><\/strong><\/h2>\n<p>\u2022 Touch-Kasse, MAC, PC, Android<br \/>\u2022 T\u00e4gliche Aufschl\u00fcsselung der Buchhaltung<br \/>\u2022 Bestandsverwaltung<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_27  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Logistik<\/h2>\n<p><strong>Einkauf, mehrere W\u00e4hrungen<\/strong><br \/>- Verwaltung der erbrachten Leistungen<br \/>- Verwaltung der Produkte<br \/>- Verwaltung der Barcodes<br \/>- Verwaltung der Konten ' Aufwand, Umsatz'<br \/>- MwSt. pro Produkt<br \/>- Verwaltung der Lieferanten<br \/>- Nebenbuchhaltung der Lieferanten  <\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_23  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_28  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p><strong>Einkauf Kredit<br \/><\/strong>- Verwaltung von Warenr\u00fccksendungen (Lieferanten)<br \/>- Verwaltung von Gutschriften (Lieferanten)<br \/>- Verwaltung von offenen Anzahlungen (Lieferanten)<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_29  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p><strong>Verkauf Kundenverwaltung, mehrere W\u00e4hrungen<br \/><\/strong>- Kundenverwaltung mit Berichten<br \/>- Nebenbuchhaltung der Kunden<br \/>- Angebote, Auftragsscheine, Arbeitsbl\u00e4tter<br \/>- Rechnungen, QR-Code - IBAN pdf<br \/>- Verwaltung mehrerer Korrespondenten pro Rechnung<br \/>- Versand von Angeboten und Rechnungen im pdf-Format per E-Mail<br \/>- Inkasso - camt054 - iso: 20022<br \/>- Tabelle der offenen Rechnungen mit Mahnungen<br \/>- Diagramm<br \/>- Versand von Dokumenten per Mail<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_30  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p><strong>Kreditverkauf<br \/><\/strong>- Verwaltung von Warenr\u00fccksendungen (Kunden)<br \/>- Verwaltung von Gutschriften (Kunden)<br \/>- Verwaltung von offenen Anzahlungen (Kunden)<br \/>- Verwaltung von Geschenkgutscheinen (Kunden)<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_24  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_31  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Finanzen<\/h2>\n<p><strong>Allgemeine Buchhaltung, mehrere W\u00e4hrungen<\/strong><br \/>- Buchungsjournal<br \/>- Konten\u00fcbersicht<br \/>- Benutzerdefinierte Konten (analytische Buchhaltung)<br \/>- Debitoren- und Kreditorenkontenverwaltung<br \/>- MwSt.-Inkrementierung und Abrechnungen<br \/>- PDF-Enddruck<br \/>- Analyse nach Konto<br \/>- MwSt.-Abrechnungen<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_32  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p><strong>Zahlungen von Rechnungen (Lieferanten)<br \/><\/strong>- Zahlungsplan<br \/>- Kreditoren-Nebenbuchhaltung<br \/>- Analyse der Zahlungen nach Periode<br \/>- Verwaltung der Abschreibungen<\/p>\n<p><strong>Zusammenf\u00fchrung von Zahlungen<\/strong><br \/>- Postfinance OPAE-FDS - iso :20022<br \/>- Banken DTA (pain001) - EBICS - iso : 20022<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_33  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Humanressourcen<\/h2>\n<p><strong>HR-Angestellte (L\u00f6hne und Geh\u00e4lter)<\/strong><br \/>- Lohnauswahl nach Berufsgruppe<br \/>- Verwaltung der Sozialversicherungsabrechnungen<br \/>- Verwaltung der Arbeitgeberkosten<br \/>- Versicherungsdokumente<br \/>- Nebenbuchhaltung<br \/>- Verbunden mit Hauptbuchhaltung <\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_12  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_25  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_divider et_pb_divider_5 et_pb_space\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"Pack_3\" class=\"et_d4_element et_pb_row et_pb_row_13  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_26  et_pb_css_mix_blend_mode et_block_column et_pb_column_empty\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_27  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_6\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"356\" height=\"141\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store.png\" alt=\"Logo, das einen Parkplatz f\u00fcr die Parkraumbewirtschaftung darstellt\" title=\"logo-logo-software-store\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store.png 356w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2024\/08\/logo-logiciel-boutique-store-300x119.png 300w\" sizes=\"(max-width: 356px) 100vw, 356px\" class=\"wp-image-80639\" \/><\/span>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_34  et_pb_text_align_center et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>SO-1600<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_28  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_button_module_wrapper et_pb_button_8_wrapper et_pb_button_alignment_right et_pb_button_alignment_tablet_center et_pb_button_alignment_phone_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_8 et_pb_bg_layout_light et_block_module\" href=\"#offre\" data-icon=\"5\">Ein Angebot anfordern<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_14 et_pb_gutters2  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_29  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_35  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2><strong>Verwaltung<\/strong><\/h2>\n<p>- Benutzerverwaltung, Passwort<br \/>- Verwaltung der Zugriffsrechte der Benutzer<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_36  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2><strong>Registrierkasse \"Software\"<br \/><\/strong><\/h2>\n<p>\u2022 Touch-Kasse, MAC, PC, Android<br \/>\u2022 T\u00e4gliche Aufschl\u00fcsselung der Buchhaltung<br \/>\u2022 Bestandsverwaltung<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_37  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Logistik<\/h2>\n<p><strong>Einkauf, mehrere W\u00e4hrungen<\/strong><br \/>- Verwaltung der erbrachten Leistungen<br \/>- Verwaltung der Produkte<br \/>- Verwaltung der Barcodes<br \/>- Verwaltung der Konten ' Aufwand, Umsatz'<br \/>- MwSt. pro Produkt<br \/>- Verwaltung der Lieferanten<br \/>- Nebenbuchhaltung der Lieferanten  <\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_38  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p><strong>Einkauf Kredit<br \/><\/strong>- Verwaltung von Warenr\u00fccksendungen (Lieferanten)<br \/>- Verwaltung von Gutschriften (Lieferanten)<br \/>- Verwaltung von offenen Anzahlungen (Lieferanten)<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_39  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p><strong>Verkauf Kundenverwaltung, mehrere W\u00e4hrungen<br \/><\/strong>- Kundenverwaltung mit Berichten<br \/>- Nebenbuchhaltung der Kunden<br \/>- Angebote, Auftragsscheine, Arbeitsbl\u00e4tter<br \/>- Rechnungen, QR-Code - IBAN pdf<br \/>- Verwaltung mehrerer Korrespondenten pro Rechnung<br \/>- Versand von Angeboten und Rechnungen im pdf-Format per E-Mail<br \/>- Inkasso - camt054 - iso: 20022<br \/>- Tabelle der offenen Rechnungen mit Mahnungen<br \/>- Diagramm<br \/>- Versand von Dokumenten per Mail<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_30  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_40  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p><strong>Kreditverkauf<br \/><\/strong>- Verwaltung von Warenr\u00fccksendungen (Kunden)<br \/>- Verwaltung von Gutschriften (Kunden)<br \/>- Verwaltung von offenen Anzahlungen (Kunden)<br \/>- Verwaltung von Geschenkgutscheinen (Kunden)<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_41  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Finanzen<\/h2>\n<p><strong>Allgemeine Buchhaltung, mehrere W\u00e4hrungen<\/strong><br \/>- Buchungsjournal<br \/>- Konten\u00fcbersicht<br \/>- Benutzerdefinierte Konten (analytische Buchhaltung)<br \/>- Debitoren- und Kreditorenkontenverwaltung<br \/>- MwSt.-Inkrementierung und Abrechnungen<br \/>- PDF-Enddruck<br \/>- Analyse nach Konto<br \/>- MwSt.-Abrechnungen<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_42  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p><strong>Zahlungen von Rechnungen (Lieferanten)<br \/><\/strong>- Zahlungsplan<br \/>- Kreditoren-Nebenbuchhaltung<br \/>- Analyse der Zahlungen nach Periode<br \/>- Verwaltung der Abschreibungen<\/p>\n<p><strong>Zusammenf\u00fchrung von Zahlungen<\/strong><br \/>- Postfinance OPAE-FDS - iso :20022<br \/>- Banken DTA (pain001) - EBICS - iso : 20022<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_31  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_43  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Humanressourcen<\/h2>\n<p><strong>HR-Angestellte (L\u00f6hne und Geh\u00e4lter)<\/strong><br \/>- Lohnauswahl nach Berufsgruppe<br \/>- Verwaltung der Sozialversicherungsabrechnungen<br \/>- Verwaltung der Arbeitgeberkosten<br \/>- Versicherungsdokumente<br \/>- Nebenbuchhaltung<br \/>- Verbunden mit Hauptbuchhaltung <\/p>\n<p><strong>HR-Zeitwirtschaft<br \/><\/strong>\u2022 Zeitmanagement in der Produktion<br \/>\u2022 Zeitmanagement der Mitarbeiter<br \/>\u2022 Verwaltung von Arbeitsbl\u00e4ttern<\/p>\n<p><strong>Personalplanung und Urlaubssaldo<br \/><\/strong>\u2022 Zeitplan, Woche, Monat, Jahr, Stundenzahl  <\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_44  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Projektmanagement<\/h2>\n<p><strong>Kundenakten<\/strong><br \/>- Zentrale Verwaltung von Kunden\/Lieferanten<br \/>- Zentrale Verwaltung von Debitorenrechnungen\/Produkten nach Lieferanten<br \/>- Speicherung von Dokumenten, die sich auf die Akte beziehen<br \/>- Verwaltung der den Zeitpl\u00e4nen zugewiesenen Daten<br \/>- Zentrale Verwaltung von CRM-Datenbl\u00e4ttern<br \/>- Zentrale Verwaltung von durch CMS erstellten Vertr\u00e4gen<br \/>- Dieses Modul, das mit dem Projektmanagement verbunden ist, bietet eine monet\u00e4re Sichtbarkeit.<\/p>\n<p><strong>Projektmanagement, Kunden<br \/><\/strong>- Projektmanagement \/ Mandate \/ W\u00e4hrungsvision<br \/>- Verfolgung von Angeboten, Rechnungen, Zahlungseing\u00e4ngen, Kunden<br \/>- Verfolgung von Angeboten, Rechnungen, Zahlungseing\u00e4ngen, Lieferanten<br \/>- Dieses Modul kann mit dem Modul Akten verkn\u00fcpft werden.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_4 et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_15  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_32  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_45  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Erhalten Sie Hardware f\u00fcr Registrierkassen<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_9_wrapper et_pb_button_alignment_left et_pb_button_alignment_tablet_center et_pb_button_alignment_phone_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_9 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/de\/2025-02-05-caisse-enregistreuse-set-fr-en-de-it-2\/\" data-icon=\"5\">Bestellen<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_33  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_46 capsule books-bullet-5  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><ul>\n<li>Touchscreen-Computer<\/li>\n<li>Kassenschublade<\/li>\n<li>Barcode-Leser<\/li>\n<li>Thermodrucker<\/li>\n<\/ul><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_5  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_16 et_pb_gutters3  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_34  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_47  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Mit MCA Store<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_48  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h3>Vereinfachen Sie Ihre Lieferkette<\/h3><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_49  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Die Lagerhaltung ist der Grundstein f\u00fcr die Gesch\u00e4ftst\u00e4tigkeit eines jeden Gesch\u00e4fts, ob es sich nun um Konfektionskleidung, Haushaltsger\u00e4te oder Schmuck handelt.<\/p>\n<p>Mit MCA Store, der Software zur Verwaltung von Gesch\u00e4ften, sind Zust\u00e4nde und Lagerbewegungen in einer intuitiven Benutzeroberfl\u00e4che klar ersichtlich. Dar\u00fcber hinaus wird Ihre Lieferkette durch automatisierte Prozesse wie Mindestbestandswarnungen und die Generierung von Lieferantenbestellungen erheblich vereinfacht.<\/p>\n<p>Statistiken und Berichte informieren Sie \u00fcber den Verkaufsstatus nach verschiedenen Kriterien, so dass Sie Ihre Bestellungen so planen k\u00f6nnen, dass Sie den Umsatz maximieren und die Kosten minimieren.<\/p>\n<p>Der Verwaltungsaufwand wird verringert, Probleme mit \u00dcber- und Unterlagerung verschwinden und die Kosten f\u00fcr die Lagerung werden gesenkt.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_6  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_17  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_35  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_3  et_pb_text_align_left  et_pb_blurb_position_left et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t<div class=\"et_pb_main_blurb_image et_pb_css_mix_blend_mode\"><span class=\"et_pb_image_wrap\"><span class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone et-pb-icon\">\uf4ce<\/span><\/span><\/div>\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t<h4 class=\"et_pb_module_header\"><span>Sichtbarkeit in Echtzeit<\/span><\/h4>\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><p>Sehen Sie auf einen Blick Ihre Lagerbest\u00e4nde und -bewegungen in Echtzeit.<\/p>\n<p>Kontrollieren Sie die Beschaffung durch das Einrichten von Mindestbestandswarnungen.<\/p>\n<p>Ermitteln Sie anhand von Statistiken die beliebtesten Produkte, den durchschnittlichen Kaufpreis oder andere relevante Elemente.<\/p><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_36  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_4  et_pb_text_align_left  et_pb_blurb_position_left et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t<div class=\"et_pb_main_blurb_image et_pb_css_mix_blend_mode\"><span class=\"et_pb_image_wrap\"><span class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone et-pb-icon\">\uf788<\/span><\/span><\/div>\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t<h4 class=\"et_pb_module_header\"><span>In ein ERP-System integrierte Kasse<\/span><\/h4>\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><p>Sparen Sie Zeit beim Kassieren mit einer intuitiven Kassensoftware.<\/p>\n<p>Sehen Sie sich alle vergangenen Transaktionen an, indem Sie die Ergebnisse nach Datum oder Produkttyp filtern.<\/p>\n<p>Drucken Sie Kassenbons, Barcode-Etiketten oder QR-Codes nach Bedarf.<\/p><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_37  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_5  et_pb_text_align_left  et_pb_blurb_position_left et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t<div class=\"et_pb_main_blurb_image et_pb_css_mix_blend_mode\"><span class=\"et_pb_image_wrap\"><span class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone et-pb-icon\">\uf109<\/span><\/span><\/div>\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t<h4 class=\"et_pb_module_header\"><span>Dokumente mit wenigen Klicks<\/span><\/h4>\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><p>Nutzen Sie eine Verkaufsschnittstelle, um alle Ihre Gesch\u00e4ftsdokumente direkt zu erstellen: Kunden- oder Lieferantenauftrag, Angebot und Rechnung.<\/p>\n<p>Automatisch erstellte Dokumente nach einer vordefinierten Layoutvorlage.<\/p>\n<p>Ideal f\u00fcr jedes Gesch\u00e4ft mit einem Just-in-time-Lagerbestand.<\/p><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_7  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_18 et_pb_gutters3  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_38  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_50  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>MCA Store<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_51  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h3>Die perfekte L\u00f6sung f\u00fcr Ihr Gesch\u00e4ft<\/h3><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_52  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>MCA Store ist eine Software zur Verwaltung von Gesch\u00e4ften, insbesondere von Non-Food-Gesch\u00e4ften. F\u00fcr die Einzelhandelsbranche konzipiert, umfasst es die gesamte kaufm\u00e4nnische Verwaltung, vom Verkauf \u00fcber den Einkauf bis hin zur Lagerverwaltung.<\/p>\n<p>Die Basis dieser Managementl\u00f6sung ist eine Registrierkasse, die mit einem zentralen Informationssystem verbunden ist.  <br \/>Alle Ihre Daten werden in einer einzigen Datenbank gesammelt, egal ob es sich um die Artikel handelt, die Sie verkaufen, um Lieferanten- oder Kundenkontakte oder um Lagerinformationen.<\/p>\n<p>Die kaufm\u00e4nnische Software optimiert Ihre Beschaffung durch automatisierte Prozesse. Es bietet Ihnen einen vollst\u00e4ndigen \u00dcberblick \u00fcber den Status und die Bewegungen von Warenbest\u00e4nden und liefert Ihnen auch Statistiken und Berichte, z.B. f\u00fcr die \u00dcberpr\u00fcfung von Verk\u00e4ufen oder Lagerbest\u00e4nden.<\/p>\n<p>Wenn Sie eine E-Commerce-Website haben, kann MCA Store mit dieser verbunden werden, um Ihre Online-Verk\u00e4ufe zu verwalten (Artikel, Best\u00e4nde, Bestellungen, etc.).<\/p>\n<p>Diese SaaS-Software macht Ihre Betriebsabl\u00e4ufe (Workflows) und Buchhaltungsvorg\u00e4nge fl\u00fcssiger. Er erspart Ihnen unn\u00f6tige Handgriffe und spart so viel Zeit.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_8 et_pb_with_background  et_pb_css_mix_blend_mode et_section_specialty et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_row et_block_row et_d4_element\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_39    et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_53  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>F\u00fcr jeden Laden die richtige L\u00f6sung<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_10_wrapper et_pb_button_alignment_left et_pb_button_alignment_tablet_center et_pb_button_alignment_phone_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_10 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/de\/berufssoftware\/mca-groceries\/\" data-icon=\"5\">Mehr erfahren<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_2_3 et_pb_column et_pb_column_40   et_pb_specialty_column  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row_inner et_pb_row_inner_0  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_pb_column et_pb_column_4_4 et_d4_element et_pb_column_inner et_pb_column_inner_0  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_54  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Die Softwarel\u00f6sung MCA Store richtet sich insbesondere an Gesch\u00e4fte im Non-Food-Bereich, wie z. B. ein Konfektions- oder M\u00f6belgesch\u00e4ft.<\/p>\n<p>Wenn Sie ein Lebensmittelgesch\u00e4ft (Lebensmittelgesch\u00e4ft, B\u00e4ckerei, Metzgerei usw.) betreiben, k\u00f6nnen Sie sich die L\u00f6sung MCA Groceries ansehen, die speziell auf den Verkauf von Lebensmitteln zugeschnitten ist.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_9  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_19  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_41  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_55  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>modulare L\u00f6sung<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_56  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h3>Basismodule, die in MCA Store enthalten sind<\/h3><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_57  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h4><span style=\"color: #702973;\">ERP - CRM - CMS<\/span>-Module<\/h4>\n<p>\u00dcbliche administrative Verwaltung f\u00fcr Einzelhandel, mit Lagerverwaltung und Verkn\u00fcpfung mit Woocommerce f\u00fcr WordPress. Verwaltung der Kundenbeziehungen, Verfolgung des Austauschs mit Kunden oder Lieferanten, Historie und Adressbuch. Vorlagen f\u00fcr Vertr\u00e4ge, Angebote, Rechnungen oder Schriftverkehr mit Ihren Ansprechpartnern.<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_20 et_pb_gutters2  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_42  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_58  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h4><span style=\"color: #702973;\">Cash Register<\/span>-Modul<\/h4>\n<p>Registrierkasse mit Verwaltung von Produkten, Kunden, Rabatten, Treuepunkten und Geschenkgutscheinen.<\/p>\n<h4><span style=\"color: #702973;\">Planning<\/span>-Modul<\/h4>\n<p>Das gesamte Planungsmanagement, insbesondere f\u00fcr die Aufgaben und Arbeitszeiten der Mitarbeiter.<\/p>\n<h4><span style=\"color: #702973;\">Reporting<\/span>-Modul<\/h4>\n<p>Dashboards, Statistiken und T\u00e4tigkeitsberichte.<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_59  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h4>Erg\u00e4nzende Modul<\/h4>\n<p>Es ist m\u00f6glich, MCA Store nach Bedarf weitere Module hinzuzuf\u00fcgen. Z\u00f6gern Sie nicht, unsere Modulseite zu besuchen, um die verf\u00fcgbaren Optionen zu studieren.<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_11_wrapper et_pb_button_alignment_left et_pb_button_alignment_tablet_center et_pb_button_alignment_phone_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_11 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/de\/die-module\/\" data-icon=\"5\">Module ansehen<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_43  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_divider_6 et_pb_space et_pb_divider_hidden\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_7 et_animated et-waypoint\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"1290\" height=\"709\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2023\/02\/logiciel-modules-mca-store-1.png\" alt=\"Pr\u00e4sentation der Module von MCA Store auf verschiedenen Bildschirmen\" title=\"\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2023\/02\/logiciel-modules-mca-store-1.png 1290w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2023\/02\/logiciel-modules-mca-store-1-1280x704.png 1280w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2023\/02\/logiciel-modules-mca-store-1-980x539.png 980w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2023\/02\/logiciel-modules-mca-store-1-480x264.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1290px, 100vw\" class=\"wp-image-64035\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_10  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_21  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_44  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_60  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Erweiterte Funktionen f\u00fcr Ihre Verwaltung<\/h2><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_22 et_animated  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_45  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_6  et_pb_text_align_left  et_pb_blurb_position_left et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t<div class=\"et_pb_main_blurb_image et_pb_css_mix_blend_mode\"><span class=\"et_pb_image_wrap\"><span class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone et-pb-icon\">N<\/span><\/span><\/div>\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t<h4 class=\"et_pb_module_header\"><span>Skalierbarkeit und kontinuierliche Verbesserung<\/span><\/h4>\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><ul>\n<li>Regelm\u00e4\u00dfige neue Funktionen und Anwendungserweiterungen, die bew\u00e4hrte Gesch\u00e4ftspraktiken f\u00f6rdern und Ihre Betriebsabl\u00e4ufe verbessern<\/li>\n<li>Neue Dienstleistungen, die in \u00dcbereinstimmung mit den von den Kunden ge\u00e4u\u00dferten Bed\u00fcrfnissen, Markt- und Technologietrends angeboten werden<\/li>\n<\/ul><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_7  et_pb_text_align_left  et_pb_blurb_position_left et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t<div class=\"et_pb_main_blurb_image et_pb_css_mix_blend_mode\"><span class=\"et_pb_image_wrap\"><span class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone et-pb-icon\">N<\/span><\/span><\/div>\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t<h4 class=\"et_pb_module_header\"><span>Einfache Integration und breite Kompatibilit\u00e4t<\/span><\/h4>\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><ul>\n<li>Schnelle und einfache Hinzuf\u00fcgung von Modulen und Diensten mit einer einzigen Datenbank als Basis<\/li>\n<li>Umfassende Interoperabilit\u00e4t mit Ihren Anwendungen von Drittanbietern, Ihrem E-Commerce-Tool, verschiedenen Betriebssystemen (Windows, Mac, Android und Linux) und Ihren Maschinen von Drittanbietern.<\/li>\n<\/ul><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_8  et_pb_text_align_left  et_pb_blurb_position_left et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t<div class=\"et_pb_main_blurb_image et_pb_css_mix_blend_mode\"><span class=\"et_pb_image_wrap\"><span class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone et-pb-icon\">N<\/span><\/span><\/div>\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t<h4 class=\"et_pb_module_header\"><span>Gemeinsame Arbeitsplattform<\/span><\/h4>\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><ul>\n<li>Synchronisation von Dokumenten und Daten mit \u00c4nderungshistorie<\/li>\n<li>Verschiedene Zugriffsebenen entsprechend der erstellten Profile<\/li>\n<\/ul><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_9  et_pb_text_align_left  et_pb_blurb_position_left et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t<div class=\"et_pb_main_blurb_image et_pb_css_mix_blend_mode\"><span class=\"et_pb_image_wrap\"><span class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone et-pb-icon\">N<\/span><\/span><\/div>\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t<h4 class=\"et_pb_module_header\"><span>Auf Ma\u00df geschneidert<\/span><\/h4>\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><ul>\n<li>Anpassbar und zug\u00e4nglich (Handy, Tablet, PC\/Mac)<\/li>\n<li>Mehrsprachige Schnittstelle, die an den Geschmack und die Farben Ihres Unternehmens angepasst werden kann (FR, EN, DE, IT)<\/li>\n<\/ul><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_46  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_10  et_pb_text_align_left  et_pb_blurb_position_left et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t<div class=\"et_pb_main_blurb_image et_pb_css_mix_blend_mode\"><span class=\"et_pb_image_wrap\"><span class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone et-pb-icon\">N<\/span><\/span><\/div>\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t<h4 class=\"et_pb_module_header\"><span>Hohe Sicherheit, Schutz, Verf\u00fcgbarkeit und Vertraulichkeit Ihrer Daten<\/span><\/h4>\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><p>Datensicherung, Zugriffsrechte und Datenspeicherung in der Schweiz in einer sicheren privaten Cloud haben f\u00fcr MCA Priorit\u00e4t:<\/p>\n<ul>\n<li>Mehr Vertrauen bei Ihren Kunden, Lieferanten und Mitarbeitern<\/li>\n<li>Bewahrter Ruf<\/li>\n<\/ul><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_11  et_pb_text_align_left  et_pb_blurb_position_left et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t<div class=\"et_pb_main_blurb_image et_pb_css_mix_blend_mode\"><span class=\"et_pb_image_wrap\"><span class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone et-pb-icon\">N<\/span><\/span><\/div>\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t<h4 class=\"et_pb_module_header\"><span>Cloud-Computing und Entmaterialisierung von Prozessen<\/span><\/h4>\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><ul>\n<li>Zugriff auf Daten an jedem Ort und zu jeder Zeit<\/li>\n<li>Geringere Kosten f\u00fcr die Infrastruktur (Computerpark)<\/li>\n<\/ul><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_blurb et_pb_blurb_12  et_pb_text_align_left  et_pb_blurb_position_left et_block_module et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_blurb_content\">\n\t\t\t\t\t<div class=\"et_pb_main_blurb_image et_pb_css_mix_blend_mode\"><span class=\"et_pb_image_wrap\"><span class=\"et-waypoint et_pb_animation_top et_pb_animation_top_tablet et_pb_animation_top_phone et-pb-icon\">N<\/span><\/span><\/div>\n\t\t\t\t\t<div class=\"et_pb_blurb_container\">\n\t\t\t\t\t\t<h4 class=\"et_pb_module_header\"><span>Entspricht den Gesetzen &amp; Vorschriften<\/span><\/h4>\n\t\t\t\t\t\t<div class=\"et_pb_blurb_description\"><ul>\n<li>Buchhaltung und Verwaltung Ihrer Gesch\u00e4fte nach den neuesten gesetzlichen Standards.<\/li>\n<li>Einhaltung von ISO 20022, DSGVO (Datenschutz-Grundverordnung), Abrechnung mit QR-Code, etc.<\/li>\n<\/ul><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_11  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_23  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_47  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_61  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Schl\u00fcsselfunktionen<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_62  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h3>Eine integrierte kaufm\u00e4nnische Verwaltung<\/h3><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_24  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_48  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_63  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h4>Verfolgung der Verk\u00e4ufe<\/h4>\n<p>Sie kassieren schnell \u00fcber das intuitive Kassensystem, per Barcode f\u00fcr gelistete Artikel oder per Tastendruck f\u00fcr freie Artikel. Sie erstellen und drucken konforme Kassenbons.<\/p>\n<p>Je nachdem, welche Art von Gesch\u00e4ft Sie verwalten, erstellen Sie Ihre verschiedenen Gesch\u00e4ftsdokumente (Angebote, Rechnungen usw.) mit wenigen Klicks von einer praktischen und ergonomischen Benutzeroberfl\u00e4che aus.<\/p>\n<p>Der gew\u00fcnschte Artikel ist nicht auf Lager ? Erstellen Sie direkt eine Lieferantenbestellung sowie die mit der Bestellung verbundene Rechnung. Der Artikel ist auf Lager, aber der Kunde kann ihn nicht selbst transportieren ? Erstellen Sie eine Kundenbestellung sowie die Verkaufsrechnung.<\/p>\n<p>Die Software speichert eine Historie der verschiedenen Transaktionen, sodass Sie Ihre Verk\u00e4ufe und Eink\u00e4ufe im Detail einsehen k\u00f6nnen.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_49  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_8 et_animated et-waypoint\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"1280\" height=\"1148\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/comptabilite-ecrans-mca-colibri.png\" alt=\"Pr\u00e4sentation der Buchhaltung in MCA Colibri auf Computer, Smartphone und Tablet.\" title=\"\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/comptabilite-ecrans-mca-colibri.png 1280w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/comptabilite-ecrans-mca-colibri-980x879.png 980w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/comptabilite-ecrans-mca-colibri-480x431.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1280px, 100vw\" class=\"wp-image-57839\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_25  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_50  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_64  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h4>Verwaltung von Produkten<\/h4>\n<p>Egal, ob Sie Kleidung, Schuhe, Haushaltsger\u00e4te oder M\u00f6bel verkaufen ... Sie legen innerhalb der Software Produktkategorien und Unterkategorien an. Sie listen in der Datenbank alle Ihre Artikel sowie m\u00f6gliche Dienstleistungen auf.<\/p>\n<p>Die Produktbl\u00e4tter enthalten verschiedene Informationen wie Bezeichnung, Verkaufspreis, Preisliste des Lieferanten, Lagerbestand und Chargennummer.<\/p>\n<p>Sie drucken Etiketten, Barcodes oder QR-Codes f\u00fcr Ihre verschiedenen Produkte.<br \/>Sie f\u00fchren die Inventur mit Hilfe eines Scanners und Barcodes durch, wobei jeder gescannte Artikel mit der erstellten Inventurliste verglichen wird.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_51  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_65  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h4>Kundenverwaltung<\/h4>\n<p>MCA Store integriert die komplette Kundenverwaltung. Dazu geh\u00f6ren Bestellungen, Lieferungen und Warenr\u00fccksendungen, aber auch Treuepunkte.<\/p>\n<p>Sie k\u00f6nnen benutzerdefinierte Preise pro Kunde zuordnen und die Zahlungen per Rechnungsstellung am Monatsende verwalten.<\/p>\n<p>Sie verf\u00fcgen \u00fcber Kundenkarten, in denen alle relevanten Informationen zusammengefasst sind (Kontaktdaten, zugeh\u00f6rige Preise, laufende Bestellungen, historische Daten usw.). Kaufhistorien sind besonders n\u00fctzlich, um den Kunden personalisierte Angebote zu machen.\n<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_26  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_52  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_9 et_animated et-waypoint\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"1312\" height=\"646\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/produits-mca-colibri.png\" alt=\"Produkt\u00fcbersicht in MCA Colibri\" title=\"\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/produits-mca-colibri.png 1312w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/produits-mca-colibri-1280x630.png 1280w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/produits-mca-colibri-980x483.png 980w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/produits-mca-colibri-480x236.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1312px, 100vw\" class=\"wp-image-57831\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_53  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_66  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h4>Lagerverwaltung<\/h4>\n<p>Sie rufen alle Bestandsinformationen direkt in der Software ab. Sie \u00fcberpr\u00fcfen die Verf\u00fcgbarkeit eines Produkts anhand einer Anfrage und f\u00fchren Lieferantenbestellungen entsprechend dem Lagerbestand durch.<\/p>\n<p>Sie werden benachrichtigt, wenn ein Artikel nicht verf\u00fcgbar ist oder wenn der Bestand eines Artikels die festgelegte Mindestbestandsgrenze erreicht hat.<\/p>\n<p>Die Shop-Management-Software hilft Ihnen bei der Verwaltung Ihrer Lieferanteneink\u00e4ufe, wobei Sie Bestellungen und Lieferungen verfolgen und die Zahlungen von Lieferantenrechnungen verwalten k\u00f6nnen.<\/p>\n<p>Wenn Sie \u00fcber mehrere Lagerstandorte verf\u00fcgen, haben Sie die Kontrolle \u00fcber die Lagerung Ihrer Best\u00e4nde und k\u00f6nnen die ben\u00f6tigten Artikel unter den verschiedenen Lagerh\u00e4usern leicht finden.\n<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_27  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_54  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_67  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h4>Buchhaltung<\/h4>\n<p>Die Filialverwaltungssoftware automatisiert die meisten Buchungsvorg\u00e4nge, um die Verwaltung zu vereinfachen. <\/p>\n<p>Die Kassendaten werden in die Buchhaltung \u00fcbertragen, um die Anzahl der erforderlichen Manipulationen zu verringern. Dasselbe gilt f\u00fcr die Daten der verschiedenen Bilanzen.<\/p>\n<p>Sie verwalten die Mehrwertsteuer innerhalb der Software, indem Sie den Mehrwertsteuersatz pro Artikel gem\u00e4\u00df den festgelegten Standards einrichten.\n<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_55  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_68  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h4>Bericht und Analyse<\/h4>\n<p>Mithilfe von Berichten, Statistiken oder Dashboards haben Sie die M\u00f6glichkeit, die von der Software gesammelte Datenmenge zu analysieren. Indem Sie die Ergebnisse nach verschiedenen Kriterien filtern, k\u00f6nnen Sie Ihre Verk\u00e4ufe oder Lagerbest\u00e4nde analysieren.<\/p>\n<p>Sie k\u00f6nnen u. a. den allgemeinen Umsatz, den Umsatz pro Filiale, pro Artikel oder pro Abteilung, die Abwesenheitsrate Ihrer Mitarbeiter, die durchschnittliche Zahlungsfrist f\u00fcr Lieferanten usw. messen.\n<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_28  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_56  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_69  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h4>Kundenkommunikation<\/h4>\n<p>Automatisierte E-Mails und SMS helfen Ihnen, die Kundenbeziehung zu pflegen. Sie leiten Informationen im Zusammenhang mit laufenden Bestellungen an Ihre Kundschaft weiter. Sie teilen die Neuigkeiten aus Ihrem Gesch\u00e4ft oder die Ferienzeiten mit.<\/p>\n<p>Auf der Grundlage des Kaufverhaltens oder des Geburtsdatums des Kunden k\u00f6nnen Sie personalisierte Werbeangebote machen.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_57  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_10 et_animated et-waypoint\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"1312\" height=\"646\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/facturation-mca-colibri.png\" alt=\"Darstellung von Rechnungen in MCA Colibri\" title=\"\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/facturation-mca-colibri.png 1312w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/facturation-mca-colibri-1280x630.png 1280w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/facturation-mca-colibri-980x483.png 980w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/facturation-mca-colibri-480x236.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1312px, 100vw\" class=\"wp-image-57843\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_29  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_58  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_11 et_animated et-waypoint\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"1312\" height=\"646\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/produits-mca-colibri.png\" alt=\"Produkt\u00fcbersicht in MCA Colibri\" title=\"\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/produits-mca-colibri.png 1312w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/produits-mca-colibri-1280x630.png 1280w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/produits-mca-colibri-980x483.png 980w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2022\/12\/produits-mca-colibri-480x236.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1312px, 100vw\" class=\"wp-image-57831\" \/><\/span>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_59  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_70  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h4>Mitarbeiterverwaltung<\/h4>\n<p>Sie verwalten verschiedene HR-Aspekte innerhalb der Filialverwaltungssoftware: Lohnverarbeitung, Verfolgung von Urlaub und Abwesenheiten, Planung etc.<\/p>\n<p>Sie erstellen die Lohnabrechnungen unter Ber\u00fccksichtigung der Lohngrundlagen, der tats\u00e4chlichen Arbeitszeit, der Sozialabgaben und anderer wichtiger Daten.<\/p>\n<p>Sie bereiten die Arbeitspl\u00e4ne der Mitarbeiter entsprechend den Vorgaben und Bed\u00fcrfnissen vor, indem Sie die zu erledigenden Aufgaben planen. Sie k\u00f6nnen die Urlaubsantr\u00e4ge mit wenigen Klicks auf der Grundlage der verbleibenden Tage best\u00e4tigen.<\/p>\n<p>Der analytische Aspekt der Verwaltungssoftware erm\u00f6glicht es Ihnen, die Abwesenheiten nach Dauer, Art der Abwesenheit oder anderen Kriterien zu untersuchen.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_12 et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_30  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_60  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_71 et_animated  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>H\u00e4ufig gestellte Fragen<\/h2><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_31 et_animated  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_61  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_toggle et_pb_toggle_0 et_animated et_pb_toggle_item  et_pb_toggle_close\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<h3 class=\"et_pb_toggle_title\">Kann ich bestimmte \u00c4nderungen an meiner Software beantragen ? <\/h3>\n\t\t\t\t<div class=\"et_pb_toggle_content clearfix\"><p>Ja. Es liegt uns am Herzen, Ihnen eine 100%ig passende Verwaltungsl\u00f6sung anzubieten. Zu diesem Zweck k\u00f6nnen unsere Entwickler bestimmte Funktionen erstellen oder \u00e4ndern, um Ihren Bed\u00fcrfnissen gerecht zu werden.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_13 et_pb_with_background  et_pb_css_mix_blend_mode et_section_specialty et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_row et_block_row et_d4_element\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_3 et_pb_column et_pb_column_62    et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_72  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Im Dienste des Kunden<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_with_border et_pb_module et_d4_element et_pb_divider et_pb_divider_7 et_animated et_pb_space\"><div class=\"et_pb_divider_internal\"><\/div><\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_2_3 et_pb_column et_pb_column_63   et_pb_specialty_column  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row_inner et_pb_row_inner_1  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_pb_column et_pb_column_4_4 et_d4_element et_pb_column_inner et_pb_column_inner_1  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_73  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Jeder Kunde von MCA Concept erh\u00e4lt Unterst\u00fctzung durch ein leistungsstarkes Team mit \u00fcber 20 Jahren Erfahrung in den Bereichen Softwaremanagement und -entwicklung.<\/p>\n<p>Unser Team kann die besten Prozesse f\u00fcr Ihr Gesch\u00e4ft abgrenzen, geeignete Funktionen anbieten und Sie bei Bedarf auch im Alltag unterst\u00fctzen.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div><div id=\"offre\" class=\"et_d4_element et_pb_section et_pb_section_14 et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_32 v-center et_animated  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_64  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_74  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Sie suchen eine Kassensoftware f\u00fcr Ihr Gesch\u00e4ft mit automatisierter Lagerverwaltung?<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_75  et_pb_text_align_center et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Erhalten Sie ein pers\u00f6nliches Angebot<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_65  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<div id=\"et_pb_contact_form_0\" class=\"et_pb_with_border et_pb_module et_d4_element et_pb_contact_form_0 et_pb_contact_form_container clearfix et_block_module\" data-form_unique_num=\"0\" data-form_unique_id=\"8536f43d-2d71-48c4-a15f-37b92b66c16f\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et-pb-contact-message\"><\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_contact\">\n\t\t\t\t\t<form class=\"et_pb_contact_form clearfix\" method=\"post\" action=\"https:\/\/mca-concept.com\/de\/wp-json\/wp\/v2\/pages\/34336\">\n\t\t\t\t\t\t<p class=\"et_d4_element et_pb_contact_field et_pb_contact_field_0 et_pb_contact_field_half\" data-id=\"entreprise\" data-type=\"input\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<label for=\"et_pb_contact_entreprise_0\" class=\"et_pb_contact_form_label\">Firma*<\/label>\n\t\t\t\t<input type=\"text\" id=\"et_pb_contact_entreprise_0\" class=\"input\" value=\"\" name=\"et_pb_contact_entreprise_0\" data-required_mark=\"required\" data-field_type=\"input\" data-original_id=\"entreprise\" placeholder=\"Firma*\">\n\t\t\t<\/p><p class=\"et_d4_element et_pb_contact_field et_pb_contact_field_1 et_pb_contact_field_half et_pb_contact_field_last\" data-id=\"nom\" data-type=\"input\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<label for=\"et_pb_contact_nom_0\" class=\"et_pb_contact_form_label\">Nachname*<\/label>\n\t\t\t\t<input type=\"text\" id=\"et_pb_contact_nom_0\" class=\"input\" value=\"\" name=\"et_pb_contact_nom_0\" data-required_mark=\"required\" data-field_type=\"input\" data-original_id=\"nom\" placeholder=\"Nachname*\">\n\t\t\t<\/p><p class=\"et_d4_element et_pb_contact_field et_pb_contact_field_2 et_pb_contact_field_half\" data-id=\"prenom\" data-type=\"input\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<label for=\"et_pb_contact_prenom_0\" class=\"et_pb_contact_form_label\">Vorname*<\/label>\n\t\t\t\t<input type=\"text\" id=\"et_pb_contact_prenom_0\" class=\"input\" value=\"\" name=\"et_pb_contact_prenom_0\" data-required_mark=\"required\" data-field_type=\"input\" data-original_id=\"prenom\" placeholder=\"Vorname*\">\n\t\t\t<\/p><p class=\"et_d4_element et_pb_contact_field et_pb_contact_field_3 et_pb_contact_field_half et_pb_contact_field_last\" data-id=\"email\" data-type=\"email\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<label for=\"et_pb_contact_email_0\" class=\"et_pb_contact_form_label\">E-Mail-Adresse*<\/label>\n\t\t\t\t<input type=\"text\" id=\"et_pb_contact_email_0\" class=\"input\" value=\"\" name=\"et_pb_contact_email_0\" data-required_mark=\"required\" data-field_type=\"email\" data-original_id=\"email\" placeholder=\"E-Mail-Adresse*\">\n\t\t\t<\/p><p class=\"et_d4_element et_pb_contact_field et_pb_contact_field_4 et_pb_contact_field_half\" data-id=\"pays\" data-type=\"input\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<label for=\"et_pb_contact_pays_0\" class=\"et_pb_contact_form_label\">Land<\/label>\n\t\t\t\t<input type=\"text\" id=\"et_pb_contact_pays_0\" class=\"input\" value=\"\" name=\"et_pb_contact_pays_0\" data-required_mark=\"required\" data-field_type=\"input\" data-original_id=\"pays\" placeholder=\"Land\">\n\t\t\t<\/p><p class=\"et_d4_element et_pb_contact_field et_pb_contact_field_5 et_pb_contact_field_half et_pb_contact_field_last\" data-id=\"tel\" data-type=\"input\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<label for=\"et_pb_contact_tel_0\" class=\"et_pb_contact_form_label\">Telefon<\/label>\n\t\t\t\t<input type=\"text\" id=\"et_pb_contact_tel_0\" class=\"input\" value=\"\" name=\"et_pb_contact_tel_0\" data-required_mark=\"not_required\" data-field_type=\"input\" data-original_id=\"tel\" placeholder=\"Telefon\">\n\t\t\t<\/p><p class=\"et_d4_element et_pb_contact_field et_pb_contact_field_6 et_pb_contact_field_half\" data-id=\"nbutil\" data-type=\"input\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<label for=\"et_pb_contact_nbutil_0\" class=\"et_pb_contact_form_label\">Anzahl der Nutzer<\/label>\n\t\t\t\t<input type=\"text\" id=\"et_pb_contact_nbutil_0\" class=\"input\" value=\"\" name=\"et_pb_contact_nbutil_0\" data-required_mark=\"not_required\" data-field_type=\"input\" data-original_id=\"nbutil\" placeholder=\"Anzahl der Nutzer\">\n\t\t\t<\/p><p class=\"et_d4_element et_pb_contact_field et_pb_contact_field_7 et_pb_contact_field_half et_pb_contact_field_last\" data-id=\"version\" data-type=\"select\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<label for=\"et_pb_contact_version_0\" class=\"et_pb_contact_form_label\">Gew\u00fcnschtes Paket<\/label>\n\t\t\t\t<select id=\"et_pb_contact_version_0\" class=\"et_pb_contact_select input\" name=\"et_pb_contact_version_0\" data-required_mark=\"not_required\" data-field_type=\"select\" data-original_id=\"version\">\n\t\t\t\t\t\t<option value=\"\">Gew\u00fcnschtes Paket<\/option><option value=\"MCA Store SO-1200\">MCA Store SO-1200<\/option><option value=\"MCA Store SO-1400\">MCA Store SO-1400<\/option><option value=\"MCA Store SO-1600\">MCA Store SO-1600<\/option>\n\t\t\t\t\t<\/select>\n\t\t\t<\/p><p class=\"et_d4_element et_pb_contact_field et_pb_contact_field_8 et_pb_contact_field_half\" data-id=\"devise\" data-type=\"select\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<label for=\"et_pb_contact_devise_0\" class=\"et_pb_contact_form_label\">W\u00e4hrung<\/label>\n\t\t\t\t<select id=\"et_pb_contact_devise_0\" class=\"et_pb_contact_select input\" name=\"et_pb_contact_devise_0\" data-required_mark=\"not_required\" data-field_type=\"select\" data-original_id=\"devise\">\n\t\t\t\t\t\t<option value=\"\">W\u00e4hrung<\/option><option value=\"CHF\">CHF<\/option><option value=\"EUR\">EUR<\/option><option value=\"USD\">USD<\/option><option value=\"GBP\">GBP<\/option><option value=\"Andere\">Andere<\/option>\n\t\t\t\t\t<\/select>\n\t\t\t<\/p><p class=\"et_d4_element et_pb_contact_field et_pb_contact_field_9 et_pb_contact_field_last\" data-id=\"info\" data-type=\"text\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<label for=\"et_pb_contact_info_0\" class=\"et_pb_contact_form_label\">Geben Sie Ihre Bed\u00fcrfnisse, die gew\u00fcnschten Funktionen usw. an.<\/label>\n\t\t\t\t<textarea name=\"et_pb_contact_info_0\" id=\"et_pb_contact_info_0\" class=\"et_pb_contact_message input\" data-required_mark=\"required\" data-field_type=\"text\" data-original_id=\"info\" placeholder=\"Geben Sie Ihre Bed\u00fcrfnisse, die gew\u00fcnschten Funktionen usw. an.\"><\/textarea>\n\t\t\t<\/p>\n\t\t\t\t\t\t<input type=\"hidden\" value=\"et_contact_proccess\" name=\"et_pb_contactform_submit_0\"\/>\n\t\t\t\t\t\t<div class=\"et_contact_bottom_container\">\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"et_pb_contact_right et_pb_contact_field\">\n\t\t\t\t<p class=\"clearfix\">\n\t\t\t\t\t<span class=\"et_pb_contact_captcha_question\">7 + 14<\/span> = <input type=\"text\" size=\"2\" class=\"input et_pb_contact_captcha\" data-first_digit=\"7\" data-second_digit=\"14\" value=\"\" name=\"et_pb_contact_captcha_0\" data-required_mark=\"required\" autocomplete=\"off\">\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<button type=\"submit\" name=\"et_builder_submit_button\" class=\"et_pb_contact_submit et_pb_button\" data-icon=\"5\">Absenden<\/button>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<input type=\"hidden\" id=\"_wpnonce-et-pb-contact-form-submitted-0\" name=\"_wpnonce-et-pb-contact-form-submitted-0\" value=\"111da67a2f\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/de\/wp-json\/wp\/v2\/pages\/34336\" \/>\n\t\t\t\t\t<\/form>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_15 et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_33  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_66  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_76  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Zusammenfassend<\/h2>\n<p>&nbsp;<\/p>\n<p><strong>MCA Store<\/strong> bietet eine umfassende <strong>Managementl\u00f6sung<\/strong> f\u00fcr <strong>Schweizer<\/strong> Unternehmen, insbesondere f\u00fcr Non-Food-Gesch\u00e4fte.<\/p>\n<p>Mit seinen verschiedenen Versionen und flexiblen Funktionen erm\u00f6glicht er es Unternehmen, ihr System an ihre spezifischen Bed\u00fcrfnisse anzupassen.<\/p>\n<p>Mit seiner integrierten Kassensoftware vereinfacht <strong>MCA Store<\/strong> die <strong>Lagerverwaltung<\/strong>, den <strong>Verkauf<\/strong> und die<strong>Beschaffung<\/strong>.<\/p>\n<p>Sie bietet einen <strong>Echtzeit-Einblick<\/strong> in die Lagerbest\u00e4nde, was dazu beitr\u00e4gt, <strong>Fehlbest\u00e4nde<\/strong> und \u00fcberm\u00e4\u00dfige Lagerkosten zu vermeiden.<\/p>\n<p>Dar\u00fcber hinaus erleichtert die Software die <strong>Generierung von Lieferantenbestellungen<\/strong> und liefert <strong>Statistiken<\/strong> und <strong>Berichte<\/strong> f\u00fcr eine fundierte Entscheidungsfindung.<\/p>\n<p>Mit Funktionen wie der in <strong>ein ERP-System integrierten Kasse<\/strong>, der Erstellung von <strong>Gesch\u00e4ftsdokumenten<\/strong> mit wenigen Klicks und der <strong>Verwaltung von Mitarbeitern<\/strong> optimiert <strong>MCA Store<\/strong> die Betriebs- und Buchhaltungsprozesse von Unternehmen und bietet gleichzeitig hohe Flexibilit\u00e4t und Datensicherheit.<\/p>\n<p>F\u00fcr Schweizer Unternehmen, die auf der Suche nach effizienten L\u00f6sungen f\u00fcr die <strong>Ladenverwaltung<\/strong> sind, ist <strong>MCA Store<\/strong> der ideale Anbieter, der wettbewerbsf\u00e4hige <strong>Preise<\/strong> und eine Vielzahl von Modulen anbietet, um den spezifischen Bed\u00fcrfnissen der <strong>Unternehmensf\u00fchrung<\/strong> gerecht zu werden.<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_34  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_67  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_77  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>erp software, crm, management software, commercial management, accounting, stocks, pme, cloud, business management, planning, pgi, saas, information system, softwarepakete, erp, softwarepaket, kundenbeziehung, managementpaket, produktionsmanagement, integriertes management, beziehungsmanagement, e-commerce, integriertes managementpaket, managementl\u00f6sung, erp solutions, enterprise resource planning, integrator, bestandsmanagement, einheitliche datenbank, erp-l\u00f6sung, r\u00fcckverfolgbarkeit, dashboards, customer relationship management, rechnungsstellung, implementierung, handel, ressourcenmanagement, microsoft dynamics, steuern, management software, open source, oracle, erp-projekt, einheit, buchhaltung, dolibarr, management softwarepakete, erp-software, unsere l\u00f6sungen, pmi, automatisierung, parametrierung, handelsmanagement-software, operativ, managementl\u00f6sungen, tpe, integrierte management-software, saas-modus, cegid, demo, automatisieren, funktional, erp und crm, ressourcenplanung, skalierbar, integrierte management-software, ebp, business intelligence, workflow, modular, unternehmensressourcen, erp open source, ergonomie, crm und erp, entscheidungsfindung, software, software, flexibilit\u00e4t, gesch\u00e4ftsprozesse, integriert, mittelst\u00e4ndische unternehmen, kleine und mittlere unternehmen, mehrere module, dynamics nav, branchen, funktionaler umfang, agilit\u00e4t, nav, supply chain, projektmanagement, beratungsunternehmen, datenbanken, analytik, erp-markt, integriertes management, verwaltung von d utilisateurs, modules de gestion, cycle de vie, r\u00e9activit\u00e9, consultant erp, logiciel de production, \u00e9critures comptables, applications informatiques, gestion des ventes, outil de gestion, solutions crm, nouvelles fonctionnalit\u00e9s, int\u00e8gre un outil, back office, permet donc de g\u00e9rer, logiciel de gestion int\u00e9gr\u00e9, permettant de g\u00e9rer l ensemble, besoins sp\u00e9cifiques, solution compl\u00e8te, collaboratif, paye, parc informatique, fonctionnelles, comptables, moteur de workflow, erp sage, \u00e9diteur de logiciel, aide \u00e0 la d\u00e9cision, int\u00e9grateurs, automatis\u00e9, int\u00e8gre l entreprise, module crm, gestion des flux, logiciels de gestion d entreprise, logiciel sap, int\u00e9gr\u00e9e au logiciel, mrp, pme pmi, ma\u00eetrise des co\u00fbts, solution de gestion int\u00e9gr\u00e9e, gestion des donn\u00e9es, jd edwards, agroalimentaire, d\u00e9veloppements sp\u00e9cifiques, d\u00e9mat\u00e9rialisation, affaire de gestion, filiales, la logistique, meilleure gestion, prestashop, modules sp\u00e9cifiques, btp, erp finance, entreprise de logiciel, plusieurs applications, \u00e9volutif, int\u00e8gre notamment, package, logiciel logistique, gestion du personnel, gain de temps, r\u00e9f\u00e9rentiel, microsoft dynamics ax, grand dictionnaire, compl\u00e8te et int\u00e9gr\u00e9e, terminologique, comptable et financi\u00e8re, dictionnaire terminologique, pourrait \u00eatre int\u00e9gr\u00e9, centralis\u00e9, activit\u00e9 commerciale, concurrentiel, sql server, gestion des commandes<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":15843,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","inline_featured_image":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"class_list":["post-34336","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Store Management Software | MCA Store<\/title>\n<meta name=\"description\" content=\"Kassieren Sie einfach und optimieren Sie Ihre Versorgung mithilfe einer umfassenden Kassensoftware mit integrierter Lagerverwaltung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mca-concept.com\/de\/berufssoftware\/mca-store\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00f6sung MCA Store\" \/>\n<meta property=\"og:description\" content=\"Kassieren Sie einfach und optimieren Sie Ihre Versorgung mithilfe einer umfassenden Kassensoftware mit integrierter Lagerverwaltung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mca-concept.com\/de\/berufssoftware\/mca-store\/\" \/>\n<meta property=\"og:site_name\" content=\"MCA Concept\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mcaconcept\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-06T13:08:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@McaConcept\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"65\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/berufssoftware\\\/mca-store\\\/\",\"url\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/berufssoftware\\\/mca-store\\\/\",\"name\":\"Store Management Software | MCA Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/#website\"},\"datePublished\":\"2022-03-10T13:08:46+00:00\",\"dateModified\":\"2025-02-06T13:08:43+00:00\",\"description\":\"Kassieren Sie einfach und optimieren Sie Ihre Versorgung mithilfe einer umfassenden Kassensoftware mit integrierter Lagerverwaltung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/berufssoftware\\\/mca-store\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mca-concept.com\\\/de\\\/berufssoftware\\\/mca-store\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/berufssoftware\\\/mca-store\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fachspezifische Software\",\"item\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/berufssoftware\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L\u00f6sung MCA Store\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/\",\"name\":\"MCA Concept\",\"description\":\"Solutions de gestion d&#039;entreprise ERP-CRM-CMS\",\"publisher\":{\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/#organization\",\"name\":\"MCA Concept\",\"url\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mca-concept.com\\\/wordpress3\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/mca-logo300px.png\",\"contentUrl\":\"https:\\\/\\\/mca-concept.com\\\/wordpress3\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/mca-logo300px.png\",\"width\":300,\"height\":156,\"caption\":\"MCA Concept\"},\"image\":{\"@id\":\"https:\\\/\\\/mca-concept.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mcaconcept\\\/\",\"https:\\\/\\\/x.com\\\/McaConcept\",\"https:\\\/\\\/www.instagram.com\\\/mcaconcept\\\/\",\"https:\\\/\\\/ch.linkedin.com\\\/company\\\/mca-concept\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC1WT0RmNiTycrnzr6FqDuPg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Store Management Software | MCA Store","description":"Kassieren Sie einfach und optimieren Sie Ihre Versorgung mithilfe einer umfassenden Kassensoftware mit integrierter Lagerverwaltung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mca-concept.com\/de\/berufssoftware\/mca-store\/","og_locale":"de_DE","og_type":"article","og_title":"L\u00f6sung MCA Store","og_description":"Kassieren Sie einfach und optimieren Sie Ihre Versorgung mithilfe einer umfassenden Kassensoftware mit integrierter Lagerverwaltung.","og_url":"https:\/\/mca-concept.com\/de\/berufssoftware\/mca-store\/","og_site_name":"MCA Concept","article_publisher":"https:\/\/www.facebook.com\/mcaconcept\/","article_modified_time":"2025-02-06T13:08:43+00:00","twitter_card":"summary_large_image","twitter_site":"@McaConcept","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"65\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mca-concept.com\/de\/berufssoftware\/mca-store\/","url":"https:\/\/mca-concept.com\/de\/berufssoftware\/mca-store\/","name":"Store Management Software | MCA Store","isPartOf":{"@id":"https:\/\/mca-concept.com\/de\/#website"},"datePublished":"2022-03-10T13:08:46+00:00","dateModified":"2025-02-06T13:08:43+00:00","description":"Kassieren Sie einfach und optimieren Sie Ihre Versorgung mithilfe einer umfassenden Kassensoftware mit integrierter Lagerverwaltung.","breadcrumb":{"@id":"https:\/\/mca-concept.com\/de\/berufssoftware\/mca-store\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mca-concept.com\/de\/berufssoftware\/mca-store\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mca-concept.com\/de\/berufssoftware\/mca-store\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mca-concept.com\/de\/"},{"@type":"ListItem","position":2,"name":"Fachspezifische Software","item":"https:\/\/mca-concept.com\/de\/berufssoftware\/"},{"@type":"ListItem","position":3,"name":"L\u00f6sung MCA Store"}]},{"@type":"WebSite","@id":"https:\/\/mca-concept.com\/de\/#website","url":"https:\/\/mca-concept.com\/de\/","name":"MCA Concept","description":"Solutions de gestion d&#039;entreprise ERP-CRM-CMS","publisher":{"@id":"https:\/\/mca-concept.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mca-concept.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mca-concept.com\/de\/#organization","name":"MCA Concept","url":"https:\/\/mca-concept.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mca-concept.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2019\/09\/mca-logo300px.png","contentUrl":"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2019\/09\/mca-logo300px.png","width":300,"height":156,"caption":"MCA Concept"},"image":{"@id":"https:\/\/mca-concept.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mcaconcept\/","https:\/\/x.com\/McaConcept","https:\/\/www.instagram.com\/mcaconcept\/","https:\/\/ch.linkedin.com\/company\/mca-concept","https:\/\/www.youtube.com\/channel\/UC1WT0RmNiTycrnzr6FqDuPg"]}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/mca-concept.com\/de\/wp-json\/wp\/v2\/pages\/34336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mca-concept.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mca-concept.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mca-concept.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mca-concept.com\/de\/wp-json\/wp\/v2\/comments?post=34336"}],"version-history":[{"count":87,"href":"https:\/\/mca-concept.com\/de\/wp-json\/wp\/v2\/pages\/34336\/revisions"}],"predecessor-version":[{"id":82741,"href":"https:\/\/mca-concept.com\/de\/wp-json\/wp\/v2\/pages\/34336\/revisions\/82741"}],"up":[{"embeddable":true,"href":"https:\/\/mca-concept.com\/de\/wp-json\/wp\/v2\/pages\/15843"}],"wp:attachment":[{"href":"https:\/\/mca-concept.com\/de\/wp-json\/wp\/v2\/media?parent=34336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}