{"id":18196,"date":"2021-10-14T13:13:33","date_gmt":"2021-10-14T12:13:33","guid":{"rendered":"https:\/\/mca-concept.com\/informazione-rete\/"},"modified":"2023-10-26T16:27:24","modified_gmt":"2023-10-26T14:27:24","slug":"informazione-rete","status":"publish","type":"page","link":"https:\/\/mca-concept.com\/it\/informazione-rete\/","title":{"rendered":"Informazioni: Reti sociali"},"content":{"rendered":"<p><div class=\"et_d4_element et_pb_section et_pb_section_0  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_0  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_0  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h1>Le nostre notizie sulle reti sociali<\/h1><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"mca-mole\" class=\"et_d4_element et_pb_section et_pb_section_1  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_1  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_1  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/mca-concept.com\/it\/modulo-mcamarina\/\" target=\"_blank\"><span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"706\" height=\"650\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/06\/illustration-reseaux-marina-mca-kale.png\" alt=\"Illustrazione informazioni di rete MCA Marina di MCA Concept\" title=\"Illustrazione Reti MCA Marina\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/06\/illustration-reseaux-marina-mca-kale.png 706w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/06\/illustration-reseaux-marina-mca-kale-480x442.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 706px, 100vw\" class=\"wp-image-13820\" \/><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_2  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_1 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>MCA Marina - per i porti turistici<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_2 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Il software, adattato alle esigenze delle attivit\u00e0 portuali, permette di avere una visione globale del piano portuale specificando la disponibilit\u00e0 e le prenotazioni dei posti barca, e di generare facilmente le fatture per i periodi di affitto. <\/br><\/br>\n<\/p>\n<ul>\n<ul>\n<li>Foto\/mappa del porto<\/li>\n<li>Navi e ormeggi associati al file del cliente\n<\/li>\n<li>Tassa di soggiorno o sconto per i visitatori regolari\n<\/li>\n<li>Fatture automatiche e periodiche\n<\/li>\n<\/ul>\n<\/ul><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_0_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_0 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/it\/modulo-mcamarina\/\" data-icon=\"5\">Ulteriori informazioni<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"mca-books\" class=\"et_d4_element et_pb_section et_pb_section_2  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_2  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_3  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_3 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>MCA Books - per biblioteche e librerie<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_4 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Una soluzione per semplificare la gestione di grandi quantit\u00e0 di libri con un sistema centralizzato che ti permette di seguire passo dopo passo l'andamento della tua collezione e avere tutte le informazioni aggiornate a portata di mano.<\/br><\/br>\n<\/p>\n<ul>\n<ul>\n<li>Gestione della registrazione<\/li>\n<li>Carte utente e carte fedelt\u00e0<\/li>\n<li>Referenze di libri<\/li>\n<li>Gestione delle scorte<\/li>\n<li>Collegato all'E-shop<\/li>\n<\/ul>\n<\/ul><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_1_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_1 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/it\/modulo-mcabooks\/\" target=\"_blank\" data-icon=\"5\">Ulteriori informazioni<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_4  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_1\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/mca-concept.com\/it\/modulo-mcabooks\/\" target=\"_blank\"><span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"706\" height=\"650\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/06\/illustration-reseaux-Books-mca-kale.png\" alt=\"Illustrazione informazioni di rete MCA Books di MCA Concept\" title=\"Illustration Reti MCA Books\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/06\/illustration-reseaux-Books-mca-kale.png 706w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/06\/illustration-reseaux-Books-mca-kale-480x442.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 706px, 100vw\" class=\"wp-image-13178\" \/><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"mca-books\" class=\"et_d4_element et_pb_section et_pb_section_3  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_3  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_5  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_2\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/mca-concept.com\/it\/modulo-mcabooks\/\" target=\"_blank\"><span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"706\" height=\"650\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/06\/illustration-reseaux-Books-mca-kale.png\" alt=\"Illustrazione informazioni di rete MCA Books di MCA Concept\" title=\"Illustration Reti MCA Books\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/06\/illustration-reseaux-Books-mca-kale.png 706w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/06\/illustration-reseaux-Books-mca-kale-480x442.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 706px, 100vw\" class=\"wp-image-13178\" \/><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_6  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_5 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>MCA Books - per biblioteche e librerie<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_6 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Una soluzione per semplificare la gestione di grandi quantit\u00e0 di libri con un sistema centralizzato che ti permette di seguire passo dopo passo l'andamento della tua collezione e avere tutte le informazioni aggiornate a portata di mano.<\/br><\/br>\n<\/p>\n<ul>\n<ul>\n<li>Gestione della registrazione<\/li>\n<li>Carte utente e carte fedelt\u00e0<\/li>\n<li>Referenze di libri<\/li>\n<li>Gestione delle scorte<\/li>\n<li>Collegato all'E-shop<\/li>\n<\/ul>\n<\/ul><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_2_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_2 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/it\/modulo-mcabooks\/\" data-icon=\"5\">Ulteriori informazioni<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"cms\" class=\"et_d4_element et_pb_section et_pb_section_4  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_4  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_7  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_3\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/mca-concept.com\/it\/modulo-cms\/\" target=\"_blank\"><span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"706\" height=\"650\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/05\/illustration-contact-cms-mca-kale.png\" alt=\"Illustrazione informazioni di rete sul CMS MCA Kale\" title=\"Illustrazione CMS\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/05\/illustration-contact-cms-mca-kale.png 706w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/05\/illustration-contact-cms-mca-kale-480x442.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 706px, 100vw\" class=\"wp-image-13074\" \/><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_8  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_7 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Gestione elettronica dei documenti<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_8 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Con lo strumento CMS di MCA Kale, puoi creare i tuoi modelli per fatture, contratti, sondaggi o lettere a clienti e dipendenti, cos\u00ec come questionari di servizio per valutare l'esperienza del cliente. <\/br><\/br>\n<\/p>\n<ul>\n<ul>\n<li>Modulo di servizio<\/li>\n<li>Questionari, sondaggi dei clienti, voti online <\/li>\n<li>Lettere standard, contratti, fatture<\/li>\n<li>Rapporti e statistiche <\/li>\n<\/ul>\n<\/ul><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_3_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_3 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/it\/modulo-cms\/\" data-icon=\"5\">Ulteriori informazioni<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"crm\" class=\"et_d4_element et_pb_section et_pb_section_5  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_5  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_9  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_9 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>CRM - gestione delle relazioni con i clienti<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_10 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Lo strumento CRM di MCA Kale permette di raccogliere e analizzare le informazioni ricevute da diversi canali per identificare e segmentare i clienti secondo i loro bisogni e interessi. Questo vi permette di implementare processi mirati e di aumentare la soddisfazione dei clienti, che a sua volta porta a una redditivit\u00e0 ottimale per la vostra azienda. <\/br><\/br>\n<\/p>\n<ul>\n<ul>\n<li>Gestione dei biglietti<\/li>\n<li>Analisi delle indagini post-vendita<\/li>\n<li>Raccolta di informazioni dal sito web<\/li>\n<li>Programmazione e invio di email automatiche<\/li>\n<\/ul>\n<\/ul><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_4_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_4 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/it\/modulo-crm\/\" data-icon=\"5\">Ulteriori informazioni<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_10  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_4\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/mca-concept.com\/it\/modulo-crm\/\" target=\"_blank\"><span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"706\" height=\"650\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/03\/illustration-contact-crm-mca-kale.png\" alt=\"Illustrazione informazioni di rete sul CRM MCA Kale\" title=\"Illustrazione CRM\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/03\/illustration-contact-crm-mca-kale.png 706w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/03\/illustration-contact-crm-mca-kale-480x442.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 706px, 100vw\" class=\"wp-image-9607\" \/><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"crm\" class=\"et_d4_element et_pb_section et_pb_section_6  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_6  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_11  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_5\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/mca-concept.com\/it\/modulo-crm\/\" target=\"_blank\"><span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"706\" height=\"650\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/03\/illustration-contact-crm-mca-kale.png\" alt=\"Illustrazione informazioni di rete sul CRM MCA Kale\" title=\"Illustrazione CRM\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/03\/illustration-contact-crm-mca-kale.png 706w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/03\/illustration-contact-crm-mca-kale-480x442.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 706px, 100vw\" class=\"wp-image-9607\" \/><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_12  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_11 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>CRM - gestione delle relazioni con i clienti<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_12 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Lo strumento CRM di MCA Kale permette di raccogliere e analizzare le informazioni ricevute da diversi canali per identificare e segmentare i clienti secondo i loro bisogni e interessi. Questo vi permette di implementare processi mirati e di aumentare la soddisfazione dei clienti, che a sua volta porta a una redditivit\u00e0 ottimale per la vostra azienda. <\/br><\/br>\n<\/p>\n<ul>\n<ul>\n<li>Gestione dei biglietti<\/li>\n<li>Analisi delle indagini post-vendita<\/li>\n<li>Raccolta di informazioni dal sito web<\/li>\n<li>Programmazione e invio di email automatiche<\/li>\n<\/ul>\n<\/ul><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_5_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_5 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/it\/modulo-consultazione\/\" data-icon=\"5\">Ulteriori informazioni<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"mca-colibri\" class=\"et_d4_element et_pb_section et_pb_section_7  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_7  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_13  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_6\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/mca-concept.com\/it\/modulo-mcacolibri\/\" target=\"_blank\"><span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"675\" height=\"650\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/05\/illustration-reseaux-colibri-mca-kale.png\" alt=\"Illustrazione informazioni di rete MCA Colibri di MCA Concept\" title=\"Illustrazione MCA Colilbri\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/05\/illustration-reseaux-colibri-mca-kale.png 675w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/05\/illustration-reseaux-colibri-mca-kale-480x462.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 675px, 100vw\" class=\"wp-image-12799\" \/><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_14  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_13 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>MCA Colibri - Per artigiani e lavoratori autonomi<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_14 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Uno strumento preciso e dinamico ma anche intuitivo che riunisce le funzionalit\u00e0 essenziali per gli artigiani e i lavoratori autonomi, dalla gestione dei prodotti e dei preventivi alla fatturazione, compresa la contabilit\u00e0 semplificata. <\/p>\n<ul>\n<ul>\n<li>Pianificazione di installazioni, revisioni o lavori di manutenzione<\/li>\n<li>Acquisti e vendite<\/li>\n<li>Contabilit\u00e0 dei pagamenti<\/li>\n<li>Fogli di presenza e dipendenti HR<\/li>\n<li>Gestione di progetti e file<\/li>\n<\/ul>\n<\/ul><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_6_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_6 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/it\/modulo-mcacolibri\/\" data-icon=\"5\">Ulteriori informazioni<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"mca-bati\" class=\"et_d4_element et_pb_section et_pb_section_8  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_8  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_15  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_15 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>MCA Stone \u2013 Per l'edilizia<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_16 et_clickable  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>La soluzione di gestione adattata al settore dell'edilizia permette il monitoraggio dell'avanzamento dei lavori nei cantieri, tenendo traccia dello storico e prestando la stessa attenzione al processo di fatturazione e alla gestione delle richieste e dei reclami di manutenzione.<\/br><\/br>\n<\/p>\n<ul>\n<ul>\n<li>Follow-up dei cantieri e sintesi del lavoro precedente <\/li>\n<li>Pianificazione di lavori e revisioni <\/li>\n<li>Contratti di abbonamento per la manutenzione <\/li>\n<li>Gestione dei preventivi, delle richieste di assistenza o dei reclami <\/li>\n<\/ul>\n<\/ul><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_7_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_7 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/it\/modulo-mcastone\/\" data-icon=\"5\">Ulteriori informazioni<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_16  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_7\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/mca-concept.com\/it\/modulo-mcastone\/\" target=\"_blank\"><span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"670\" height=\"650\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/04\/illustration-reseaux-stone-mca-kale.png\" alt=\"Illustrazione informazioni di rete MCA Stone di MCA Concept\" title=\"Illustrazione MCA Stone\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/04\/illustration-reseaux-stone-mca-kale.png 670w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/04\/illustration-reseaux-stone-mca-kale-480x466.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 670px, 100vw\" class=\"wp-image-12342\" \/><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"mca-bati\" class=\"et_d4_element et_pb_section et_pb_section_9  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_9  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_17  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_8\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/mca-concept.com\/it\/modulo-mcastone\/\" target=\"_blank\"><span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"670\" height=\"650\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/04\/illustration-reseaux-stone-mca-kale.png\" alt=\"Illustrazione informazioni di rete MCA Stone di MCA Concept\" title=\"Illustrazione MCA Stone\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/04\/illustration-reseaux-stone-mca-kale.png 670w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/04\/illustration-reseaux-stone-mca-kale-480x466.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 670px, 100vw\" class=\"wp-image-12342\" \/><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_18  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_17 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>MCA Bati - Per l'edilizia<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_18 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>La soluzione di gestione adattata al settore dell'edilizia permette il monitoraggio dell'avanzamento dei lavori nei cantieri, tenendo traccia dello storico e prestando la stessa attenzione al processo di fatturazione e alla gestione delle richieste e dei reclami di manutenzione.<\/p>\n<ul>\n<ul>\n<li>Follow-up dei cantieri e sintesi del lavoro precedente<\/li>\n<li>Pianificazione di lavori e revisioni<\/li>\n<li>Contratti di abbonamento per la manutenzione<\/li>\n<li>Gestione dei preventivi, delle richieste di assistenza o dei reclami<\/li>\n<\/ul>\n<\/ul><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_8_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_8 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/it\/modulo-mcastone\/\" data-icon=\"5\">Ulteriori informazioni<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"mca-flame\" class=\"et_d4_element et_pb_section et_pb_section_10  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_10  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_19  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_9\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/mca-concept.com\/it\/modulo-mcaflame\/\" target=\"_blank\"><span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"675\" height=\"650\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/04\/illustration-reseaux-flame-mca-kale.png\" alt=\"Illustrazione informazioni di rete MCA Flame di MCA Concept\" title=\"Illustrazione MCA Flame\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/04\/illustration-reseaux-flame-mca-kale.png 675w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/04\/illustration-reseaux-flame-mca-kale-480x462.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 675px, 100vw\" class=\"wp-image-13426\" \/><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_20  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_19 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>MCA Flame - Per gli ingegneri del riscaldamento e dei sanitari<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_20 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Lo strumento di gestione per il settore del riscaldamento e dei sanitari offre una semplice organizzazione dei servizi di installazione, manutenzione e riparazione grazie a una precisa programmazione degli appuntamenti e a un sistema di fatturazione che facilita la gestione dei servizi in forma di abbonamento. <\/br><\/br>\n<\/p>\n<ul>\n<ul>\n<li>Pianificazione di installazioni, revisioni o lavori di manutenzione<\/li>\n<li>Abbonamenti per tecnici <\/li>\n<li>Fatture di abbonamento per i clienti <\/li>\n<li>Contratti di manutenzione<\/li>\n<\/ul>\n<\/ul><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_9_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_9 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/it\/modulo-mcaflame\/\" data-icon=\"5\">Ulteriori informazioni<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"facturation fatturazione\" class=\"et_d4_element et_pb_section et_pb_section_11  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_11  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_21  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_21 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Fatturazione<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_22 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Gestione della fatturazione semplice e chiara, puoi controllare facilmente lo stato di tutti i pagamenti e trasformare automaticamente un preventivo in una fattura.<\/p>\n<ul>\n<ul>\n<li>QR<\/li>\n<li>PDF \/ XLS \/ MAIL<\/li>\n<li>Abbonamenti<\/li>\n<li>Anticipi, liquidazioni e detrazioni.<\/li>\n<li>Promemoria non pagati<\/li>\n<li>Collegato al file client<\/li>\n<\/ul>\n<\/ul><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_10_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_10 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/it\/modulo-facturation\/\" target=\"_blank\" data-icon=\"5\">Ulteriori informazioni<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_22  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_10\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/mca-concept.com\/it\/modulo-facturation\/\" target=\"_blank\"><span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"667\" height=\"650\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/04\/illustration-contact-facturation-mca-kale.png\" alt=\"Illustrazione informazioni di rete sulla fatturazione di MCA Kale\" title=\"Illustrazione Facturation\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/04\/illustration-contact-facturation-mca-kale.png 667w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/04\/illustration-contact-facturation-mca-kale-480x468.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 667px, 100vw\" class=\"wp-image-10725\" \/><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"facturation fatturazione\" class=\"et_d4_element et_pb_section et_pb_section_12  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_12  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_23  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_11\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/mca-concept.com\/it\/modulo-facturation\/\" target=\"_blank\"><span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"667\" height=\"650\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/04\/illustration-contact-facturation-mca-kale.png\" alt=\"Illustrazione del modulo di contatto per la fatturazione di MCA Kale\" title=\"Illustrazione Facturation\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/04\/illustration-contact-facturation-mca-kale.png 667w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/04\/illustration-contact-facturation-mca-kale-480x468.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 667px, 100vw\" class=\"wp-image-10725\" \/><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_24  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_23 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Fatturazione<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_24 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Gestione della fatturazione semplice e chiara, puoi controllare facilmente lo stato di tutti i pagamenti e trasformare automaticamente un preventivo in una fattura.<\/br><\/br>\n<\/p>\n<ul>\n<ul>\n<li>QR<\/li>\n<li>PDF \/ XLS \/ MAIL<\/li>\n<li>Abbonamenti<\/li>\n<li>Anticipi, liquidazioni e detrazioni.<\/li>\n<li>Promemoria non pagati<\/li>\n<li>Collegato al file client<\/li>\n<\/ul>\n<\/ul><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_11_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_11 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/it\/modulo-facturation\/\" data-icon=\"5\">Ulteriori informazioni<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"hr\" class=\"et_d4_element et_pb_section et_pb_section_13  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_13  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_25  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_12\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/mca-concept.com\/it\/modulo-hr\/\" target=\"_blank\"><span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"707\" height=\"650\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/03\/illustration-contact-rh-mca-kale.png\" alt=\"Illustrazione informazioni di rete su MCA Kale HR\" title=\"Illustrazione HR\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/03\/illustration-contact-rh-mca-kale.png 707w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/03\/illustration-contact-rh-mca-kale-480x441.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 707px, 100vw\" class=\"wp-image-9663\" \/><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_26  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_25 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>HR - Gestione del personale<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_26 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Evitate lo stress e risparmiate tempo usando uno strumento centralizzato per gestire le ore di lavoro, programmare e distribuire i compiti ai dipendenti ed elaborare il libro paga.<\/br><\/br>\n<\/p>\n<ul>\n<ul>\n<li>Gestione del tempo dei dipendenti tenendo conto delle ferie e dei giorni festivi<\/li>\n<li>Salari e conti spese relativi alla contabilit\u00e0 generale<\/li>\n<li>Pianificazione e organizzazione dei compiti<\/li>\n<\/ul>\n<\/ul><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_12_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_12 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/it\/modulo-hr\/\" data-icon=\"5\">Ulteriori informazioni<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"consultazione\" class=\"et_d4_element et_pb_section et_pb_section_14  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_14  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_27  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_27 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Consultazione<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_28 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Niente pi\u00f9 problemi, con noi troverete solo soluzioni.<\/p>\n<p>Il nostro team di tecnici \u00e8 sempre disponibile per rispondere a qualsiasi dubbio o preoccupazione e, soprattutto, per supportarvi nella digitalizzazione dei vostri processi operativi.<\/p>\n<p>Contattateci per scoprire quale soluzione \u00e8 pi\u00f9 adatta alle dimensioni della vostra azienda con caratteristiche specifiche del settore.<\/p>\n<p>&nbsp;<\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_13_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_13 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/it\/modulo-consultazione\/\" data-icon=\"5\">Contattateci<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_28  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_13\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/mca-concept.com\/it\/modulo-consultazione\/\" target=\"_blank\"><span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"706\" height=\"650\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/05\/illustration-contact-consultation-mca-kale.png\" alt=\"Illustrazione informazioni reti di consultazione di MCA Kale\" title=\"Illustrazione Consultazione\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/05\/illustration-contact-consultation-mca-kale.png 706w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/05\/illustration-contact-consultation-mca-kale-480x442.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 706px, 100vw\" class=\"wp-image-13007\" \/><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div id=\"consultazione\" class=\"et_d4_element et_pb_section et_pb_section_15  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_15  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_29  et_pb_css_mix_blend_mode et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_image et_pb_image_14\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/mca-concept.com\/it\/modulo-consultazione\/\" target=\"_blank\"><span class=\"et_pb_image_wrap \"><img decoding=\"async\" width=\"706\" height=\"650\" src=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/05\/illustration-contact-consultation-mca-kale.png\" alt=\"Illustrazione informazioni reti di consultazione di MCA Kale\" title=\"Illustrazione Consultazione\" srcset=\"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/05\/illustration-contact-consultation-mca-kale.png 706w, https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2021\/05\/illustration-contact-consultation-mca-kale-480x442.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 706px, 100vw\" class=\"wp-image-13007\" \/><\/span><\/a>\n\t\t\t<\/div>\n\t\t\t<\/div><div class=\"et_d4_element et_pb_column_1_2 et_pb_column et_pb_column_30  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_29 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Consultazione<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_30 et_clickable  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Niente pi\u00f9 problemi, con noi troverete solo soluzioni.<br \/>\nIl nostro team di tecnici \u00e8 sempre disponibile per rispondere a qualsiasi dubbio o preoccupazione e, soprattutto, per supportarvi nella digitalizzazione dei vostri processi operativi. Contattateci per scoprire quale soluzione \u00e8 pi\u00f9 adatta alle dimensioni della vostra azienda con caratteristiche specifiche del settore.<\/p>\n<p><\/br><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_14_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_14 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/mca-concept.com\/it\/modulo-consultazione\/\" data-icon=\"5\">Contattateci<\/a>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_16 et_pb_with_background  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_16  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_31  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_31  et_pb_text_align_left et_pb_text_align_center-tablet et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>Per riassumere<\/h2>\n<p><span>MCA Concept offre una gamma completa di <\/span><strong>soluzioni di gestione<\/strong><span> su misura per le esigenze specifiche delle aziende in Svizzera.<\/span><\/p>\n<p><span>Il loro <\/span><strong>software<\/strong><span>MCA Marina per i porti turistici, MCA Books per le biblioteche e le librerie, MCA Kale per la gestione elettronica dei documenti, MCA Colibri per gli artigiani e i liberi professionisti, MCA Stone per l'edilizia e MCA Flame per i termotecnici e i sanitari, sono tutti progettati per ottimizzare l'efficienza e l'efficacia della vostra attivit\u00e0.  <\/span><strong>gestione delle risorse<\/strong><span>semplificare i <\/span><strong>processi di fatturazione<\/strong><span>migliorare <\/span><strong>le relazioni con i clienti<\/strong><span> con strumenti CRM ad alte prestazioni e semplificare la <\/span><strong>gestione del personale<\/strong><span>.<\/span><\/p>\n<p><span>Queste soluzioni includono funzioni avanzate come la generazione automatica delle fatture, la gestione degli abbonamenti, la programmazione dei lavori e molto altro ancora.<\/span><\/p>\n<p><span>Che siate una piccola impresa o una grande azienda, MCA Concept offre soluzioni su misura per soddisfare le esigenze specifiche della vostra azienda. <\/span><strong>attivit\u00e0<\/strong><span>.<\/span><\/p>\n<p><span>Il loro team di tecnici \u00e8 a disposizione per aiutarvi a digitalizzare i vostri processi operativi, garantendo una gestione efficiente e ottimale della vostra attivit\u00e0.<\/span><\/p>\n<p><span>Contattate MCA Concept per scoprire la soluzione pi\u00f9 adatta alla vostra azienda, con caratteristiche specifiche per il vostro settore.<\/span><strong>attivit\u00e0<\/strong><span>.<\/span><\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_17  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_32  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_32  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p>Software ERP, CRM, software gestionale, gestione commerciale, contabilit\u00e0, azioni, PMI, cloud, gestione aziendale, pianificazione, erp, saas, sistema informativo, pacchetti software, erp, pacchetto software, relazioni con i clienti, software di gestione, gestione della produzione, gestione integrata, gestione delle relazioni, e-commerce, pianificazione delle risorse aziendali, soluzione di gestione, soluzioni ERP, pianificazione delle risorse aziendali, integratore, gestione dell'inventario,  Database unico, soluzione ERP, tracciabilit\u00e0, dashboard, gestione delle relazioni con i clienti, fatturazione, implementazione, trading, gestione delle risorse, dinamiche Microsoft, pilota, software gestionale, open source, oracolo, progetto ERP, unicit\u00e0, gestione contabile, Dolibarr, software gestionale, software ERP, le nostre soluzioni, PMI, automazione, parametrizzazione, software di gestione commerciale, operazioni, soluzioni gestionali, TPE, sistema di pianificazione delle risorse aziendali,  SaaS, CEGID, Demo, Automatizzare, Funzionale, ERP e CRM, Pianificazione delle risorse, Scalabile, Pianificazione delle risorse aziendali, EBP, Business Intelligence, Flusso di lavoro, Modulare, Risorse aziendali, ERP open source, Ergonomia, CRM e ERP, BI, Software, Software, Flessibilit\u00e0, Processi aziendali, Integrato, Medie, Piccole e medie imprese, Moduli multipli, Dynamics NAV, Industria, Ambito funzionale, Agilit\u00e0, NAV,  Supply Chain, Project Management, Consulenti, Database, Analytics, Mercato ERP, Gestione Integrata, Gestione Risorse Umane, Reporting, Funzionale, Gestione Acquisti, Contabilit\u00e0, Diversi Moduli, Pacchetto ERP, Microsoft Dynamics NAV, ERP SaaS, Set di Processi, Interfacce, Software di Gestione Aziendale, Reparto IT, Centralizzare, Dynamics Ax, Strumenti di Gestione, Servizi Diversi, Processi Aziendali, Giorno in Tempo Reale,  SAP ERP, copertura funzionale, processo decisionale, openerp, integrato nel software, moduli indipendenti, processi aziendali, soluzione software, magazzini, project manager, dolibarr erp, gestione finanziaria, modulo di gestione, processi aziendali, wms, centralizzato, gestione dell'inventario, supply chain, processi operativi, software aziendale, strumento integrato, specifiche ERP, il tuo business, data entry, controllo di gestione,  Medie imprese, tesoreria, soluzioni software, software aziendale, software CRM, Sage ERP, sistemi ERP, voci, configurabile, flessibile, opensource, tutti i servizi, consulenza, integrato con software, VSE e PMI, processi di lavoro, integrato con software, moduli software, piccole e medie imprese, gestione dei progetti, mySQL, configurazione del software, sviluppatore, risparmiare tempo, implementazione del software,  Centralizzazione, soluzione CRM, EDI, software aziendale, licenze, CEGID ERP, introduzione, numero D Utenti, moduli gestionali, ciclo di vita, reattivit\u00e0, consulente ERP, software di produzione, scritture contabili, applicazioni informatiche, gestione vendite, strumento di gestione, soluzioni CRM, nuove funzionalit\u00e0, integra uno strumento, back office, consente di gestire, software gestionale integrato, che consente di gestire tutto, esigenze specifiche, soluzione completa, collaborativo, buste paga, apparecchiature informatiche, funzionale, contabilit\u00e0,  motore di workflow, sage erp, software publisher, supporto alle decisioni, integratori, automatizzato, enterprise integrato, modulo CRM, gestione dei flussi, software di gestione aziendale, software SAP, software integrato, MRP, PMI PMI, controllo dei costi, soluzione di gestione integrata, gestione dati, JD Edwards, agroalimentare, sviluppi specifici, dematerializzazione, gestione aziendale, filiali, logistica,  migliore gestione, prestashop, moduli specifici, costruzione, erp finanza, societ\u00e0 di software, applicazioni multiple, scalabile, integrato, pacchetto, software logistico, gestione del personale, risparmio di tempo, repository, microsoft dynamics ax, dizionario grande, completo e integrato, terminologia, contabilit\u00e0 e finanza, dizionario terminologico, potrebbe essere integrato, centralizzato, attivit\u00e0 commerciale, competitivo, sql server, gestione ordini<\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","inline_featured_image":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"class_list":["post-18196","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Informazioni sulle nostre soluzioni | MCA Concept<\/title>\n<meta name=\"description\" content=\"Scoprite le numerose possibilit\u00e0 offerte dal software di MCA Concept. Link alle notizie trasmesse sulle nostre reti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mca-concept.com\/it\/informazione-rete\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informazioni: Reti sociali\" \/>\n<meta property=\"og:description\" content=\"Scoprite le numerose possibilit\u00e0 offerte dal software di MCA Concept. Link alle notizie trasmesse sulle nostre reti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mca-concept.com\/it\/informazione-rete\/\" \/>\n<meta property=\"og:site_name\" content=\"MCA Concept\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mcaconcept\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-26T14:27:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@McaConcept\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"32 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mca-concept.com\\\/it\\\/informazione-rete\\\/\",\"url\":\"https:\\\/\\\/mca-concept.com\\\/it\\\/informazione-rete\\\/\",\"name\":\"Informazioni sulle nostre soluzioni | MCA Concept\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mca-concept.com\\\/it\\\/#website\"},\"datePublished\":\"2021-10-14T12:13:33+00:00\",\"dateModified\":\"2023-10-26T14:27:24+00:00\",\"description\":\"Scoprite le numerose possibilit\u00e0 offerte dal software di MCA Concept. Link alle notizie trasmesse sulle nostre reti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mca-concept.com\\\/it\\\/informazione-rete\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mca-concept.com\\\/it\\\/informazione-rete\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mca-concept.com\\\/it\\\/informazione-rete\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mca-concept.com\\\/it\\\/nuova-casa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informazioni: Reti sociali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mca-concept.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/mca-concept.com\\\/it\\\/\",\"name\":\"MCA Concept\",\"description\":\"Solutions de gestion d&#039;entreprise ERP-CRM-CMS\",\"publisher\":{\"@id\":\"https:\\\/\\\/mca-concept.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mca-concept.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mca-concept.com\\\/it\\\/#organization\",\"name\":\"MCA Concept\",\"url\":\"https:\\\/\\\/mca-concept.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mca-concept.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mca-concept.com\\\/wordpress3\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/mca-logo300px.png\",\"contentUrl\":\"https:\\\/\\\/mca-concept.com\\\/wordpress3\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/mca-logo300px.png\",\"width\":300,\"height\":156,\"caption\":\"MCA Concept\"},\"image\":{\"@id\":\"https:\\\/\\\/mca-concept.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mcaconcept\\\/\",\"https:\\\/\\\/x.com\\\/McaConcept\",\"https:\\\/\\\/www.instagram.com\\\/mcaconcept\\\/\",\"https:\\\/\\\/ch.linkedin.com\\\/company\\\/mca-concept\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC1WT0RmNiTycrnzr6FqDuPg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Informazioni sulle nostre soluzioni | MCA Concept","description":"Scoprite le numerose possibilit\u00e0 offerte dal software di MCA Concept. Link alle notizie trasmesse sulle nostre reti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mca-concept.com\/it\/informazione-rete\/","og_locale":"it_IT","og_type":"article","og_title":"Informazioni: Reti sociali","og_description":"Scoprite le numerose possibilit\u00e0 offerte dal software di MCA Concept. Link alle notizie trasmesse sulle nostre reti.","og_url":"https:\/\/mca-concept.com\/it\/informazione-rete\/","og_site_name":"MCA Concept","article_publisher":"https:\/\/www.facebook.com\/mcaconcept\/","article_modified_time":"2023-10-26T14:27:24+00:00","twitter_card":"summary_large_image","twitter_site":"@McaConcept","twitter_misc":{"Tempo di lettura stimato":"32 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mca-concept.com\/it\/informazione-rete\/","url":"https:\/\/mca-concept.com\/it\/informazione-rete\/","name":"Informazioni sulle nostre soluzioni | MCA Concept","isPartOf":{"@id":"https:\/\/mca-concept.com\/it\/#website"},"datePublished":"2021-10-14T12:13:33+00:00","dateModified":"2023-10-26T14:27:24+00:00","description":"Scoprite le numerose possibilit\u00e0 offerte dal software di MCA Concept. Link alle notizie trasmesse sulle nostre reti.","breadcrumb":{"@id":"https:\/\/mca-concept.com\/it\/informazione-rete\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mca-concept.com\/it\/informazione-rete\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mca-concept.com\/it\/informazione-rete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mca-concept.com\/it\/nuova-casa\/"},{"@type":"ListItem","position":2,"name":"Informazioni: Reti sociali"}]},{"@type":"WebSite","@id":"https:\/\/mca-concept.com\/it\/#website","url":"https:\/\/mca-concept.com\/it\/","name":"MCA Concept","description":"Solutions de gestion d&#039;entreprise ERP-CRM-CMS","publisher":{"@id":"https:\/\/mca-concept.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mca-concept.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mca-concept.com\/it\/#organization","name":"MCA Concept","url":"https:\/\/mca-concept.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mca-concept.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2019\/09\/mca-logo300px.png","contentUrl":"https:\/\/mca-concept.com\/wordpress3\/wp-content\/uploads\/2019\/09\/mca-logo300px.png","width":300,"height":156,"caption":"MCA Concept"},"image":{"@id":"https:\/\/mca-concept.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mcaconcept\/","https:\/\/x.com\/McaConcept","https:\/\/www.instagram.com\/mcaconcept\/","https:\/\/ch.linkedin.com\/company\/mca-concept","https:\/\/www.youtube.com\/channel\/UC1WT0RmNiTycrnzr6FqDuPg"]}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/mca-concept.com\/it\/wp-json\/wp\/v2\/pages\/18196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mca-concept.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mca-concept.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mca-concept.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mca-concept.com\/it\/wp-json\/wp\/v2\/comments?post=18196"}],"version-history":[{"count":12,"href":"https:\/\/mca-concept.com\/it\/wp-json\/wp\/v2\/pages\/18196\/revisions"}],"predecessor-version":[{"id":74603,"href":"https:\/\/mca-concept.com\/it\/wp-json\/wp\/v2\/pages\/18196\/revisions\/74603"}],"wp:attachment":[{"href":"https:\/\/mca-concept.com\/it\/wp-json\/wp\/v2\/media?parent=18196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}